{"id":8867,"date":"2022-02-26T21:53:03","date_gmt":"2022-02-26T13:53:03","guid":{"rendered":"https:\/\/www.shining-dc.com.tw\/all-ceramic-crown\/"},"modified":"2023-11-13T17:09:00","modified_gmt":"2023-11-13T09:09:00","slug":"all-ceramic-crown","status":"publish","type":"page","link":"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/","title":{"rendered":"\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8867\" class=\"elementor elementor-8867\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c6c28e0 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"c6c28e0\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebc6048\" data-id=\"ebc6048\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a728cc elementor-widget elementor-widget-spacer\" data-id=\"4a728cc\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84b7d64 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"84b7d64\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"844\" height=\"85\" src=\"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2023\/11\/ao3oa-fgks8.webp\" class=\"attachment-full size-full wp-image-9039\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5e3fbc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5e3fbc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12259af\" data-id=\"12259af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ca45de elementor-align-left elementor-widget elementor-widget-raven-breadcrumbs\" data-id=\"2ca45de\" data-element_type=\"widget\" data-widget_type=\"raven-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"raven-breadcrumbs raven-breadcrumbs-default\"><div class=\"breadcrumb\">\t\t\t\t<div class=\"breadcrumb-item active\" aria-current=\"page\"><span>Home<\/span><\/div>\r\n\r\n\t\t\t\t<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c4c0a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c4c0a0\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6508fd4\" data-id=\"6508fd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce01ad7 elementor-widget elementor-widget-text-editor\" data-id=\"ce01ad7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>All-ceramic crown<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f60662e elementor-widget elementor-widget-text-editor\" data-id=\"f60662e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-004907c elementor-widget elementor-widget-html\" data-id=\"004907c\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"http:\/\/schema.org\",\r\n  \"@type\": \"MediaObject\",\r\n \"name\" : \"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012022\u6750\u8cea\uff06\u58fd\u547d\",\r\n  \"aggregateRating\": {\r\n    \"@type\": \"AggregateRating\",\r\n    \"ratingValue\" : \"5\", \r\n\t\"bestRating\" : \"5\", \r\n\t\"ratingCount\" : \"1012\" \r\n  }}\r\n<\/script>\r\n<script type=\"application\/ld+json\">\r\n{ \r\n\t\"@context\" : \"http:\/\/schema.org\", \r\n\t\"headline\" : \"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012022\u6750\u8cea\uff06\u58fd\u547d\", \r\n\t\"image\" : \"\", \r\n\t\"@type\" : \"Article\", \r\n\t\"name\" : \"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012022\u6750\u8cea\uff06\u58fd\u547d\", \r\n\t\"author\" : { \r\n\t\"@type\" : \"Person\", \r\n\t\"name\" : \"\u674e\u6606\u7e09\u7259\u91ab\u5e2b\u9662\u9577 \" \r\n\t}, \r\n\t\"datePublished\" : \"2021-11-12\", \r\n\t\"articleSection\" : \"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012022\u6750\u8cea\uff06\u58fd\u547d\", \r\n\t\"articleBody\" : \"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012022\u6750\u8cea\uff06\u58fd\u547d\uff0c2022\u5e74\u60a8\u9084\u5728\u70ba\u6839\u7ba1\u6cbb\u7642\u5f8c\uff0c\u8b8a\u9ed1\u7684\u7259\u9f52\u96e3\u904e\u55ce\uff1f\u9084\u662f\uff0c\u60a8\u6709\u7259\u9f52\u7f3a\u4e00\u89d2\u7684\u56f0\u64fe\u5462\uff1f\u8fd1\u5e74\u4f86\uff0c\u4f7f\u7528\u5168\u74f7\u51a0\u70ba\u7259\u9f52\u4fee\u5fa9\u7684\u6bd4\u4f8b\u9010\u5e74\u5347\u9ad8\u3002 \u7a76\u7adf\uff0c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\u5462\uff1f\u807d\u8aaa\u5168\u74f7\u51a0\u9084\u53ef\u4ee5\u7576\u4f5c\u300e\u5047\u7259\u3001\u7259\u5957\u3001\u7f8e\u767d\u8cbc\u7247\u300f\u4f7f\u7528\u8036\uff01\u8b93\u6211\u5011\u4e00\u8d77\u4f86\u4e86\u89e3\u5427\uff5e\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u904e\u53bb\uff0c\u50b3\u7d71\u7684\u7259\u51a0\u50c5\u300e\u5916\u90e8\u70ba\u74f7\u8cea\uff0c\u5167\u90e8\u70ba\u91d1\u5c6c\u300f\uff0c\u800c\u5168\u74f7\u51a0\u7259\u5957\u5247\u662f\u7531\u5167\u800c\u5916\u300e\u7686\u662f\u74f7\u584a\u300f\uff0c\u800c\u5168\u74f7\u51a0\u7259\u5957\u6700\u5927\u7684\uff15\u5927\u512a\u52e2\uff0c\u5c31\u662f\u4e0d\u542b\u4efb\u4f55\u91d1\u5c6c\u6210\u5206\u3001\u8207\u4eba\u9ad4\u7684\u76f8\u5bb9\u6027\u8f03\u4f73\u3001\u6c92\u6709\u81f4\u764c\u7591\u616e\u3001\u4e0d\u5bb9\u6613\u6709\u767c\u708e\u6216\u904e\u654f\u73fe\u8c61\u3001\u7259\u9f66\u908a\u7de3\u4e0d\u6703\u8b8a\u8272\u3002\u800c\u4e14\uff0c\u5168\u74f7\u51a0\u7684\u8272\u6fa4\u8207\u771f\u7259\u8f03\u70ba\u63a5\u8fd1\uff0c\u6240\u4ee5\uff0c\u4e5f\u6709\u4e0d\u5c11\u4eba\u5c07\u5168\u74f7\u51a0\u7f8e\u767d\u8cbc\u7247\u4f5c\u70ba\u7f8e\u767d\u7684\u4e00\u7a2e\u9078\u64c7\uff0c\u82e5\u60f3\u4e86\u89e3\u5176\u4ed6\u7259\u9f52\u7f8e\u767d\u77e5\u8b58\uff0c\u53ef\u53c3\u8003\u6b64\u7bc7\u300a\u53f0\u4e2d\u7259\u9f52\u7f8e\u767d\u63a8\u85a6\u3014\u50f9\u683c\u516c\u958b\u3015\u51b7\u5149\/\u5674\u7802\/\u5c45\u5bb6\/\u8cbc\u7247-\u55a8\u7c92\u6676\u7259\u91ab\u300b\u3002\u76f8\u4fe1\u5927\u5bb6\u90fd\u8feb\u4e0d\u53ca\u5f85\u60f3\u4e86\u89e32022\u5168\u74f7\u51a0\u50f9\u9322\u662f\u591a\u5c11\uff1fPTT\u9109\u6c11\u5c0d\u65bc\u50f9\u683c\u4e5f\u6709\u7591\u60d1\uff0c\u9019\u908a\u70ba\u5927\u5bb6\u7d71\u6574\u3002\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\u591a\u5c11\uff1f\u6709PTT\u9109\u6c11\u8a62\u554f\u300e\u7259\u5957\u5168\u74f7\u51a0\uff12\u842c\uff15\uff0c\u6b63\u5e38\u55ce\uff1f\u300f\u3001\u300e\u5168\u74f7\u51a0\uff11\uff12\uff10\uff10\uff10\u5143\u5408\u7406\u55ce\uff1f\u300f \u9996\u5148\uff0c\u5148\u8ddf\u5927\u5bb6\u8aaa\u660e\u5f71\u97ff\u5168\u74f7\u51a0\u50f9\u683c\u7684\u4e3b\u8981\u56e0\u7d20\uff0c\u6709\u4ee5\u4e0b\u5e7e\u500b\u2193\u2193\u2193 \u65bd\u505a\u624b\u8853\u7684\u7259\u9f52\u4f4d\u7f6e\uff08\u8207\u624b\u8853\u96e3\u6613\u5ea6\u6709\u95dc\uff09\u3001\u5168\u74f7\u51a0\u54c1\u724c\uff08\u5e38\u898b\u54c1\u724c\u5305\u542bCercon\u30013M Lava\u3001TDS\u3001Wieland\u3001Vita\u3001E-max\u3001Celtra Duo\uff09\u3001\u5168\u74f7\u51a0\u6750\u8cea\uff08\u786c\u5ea6\uff1a\u4e8c\u6c27\u5316\u92ef\u3009\u4e8c\u77fd\u9178\u92f0\uff09\u3001\u8a3a\u6240\u5730\u5340\uff08\u76f8\u8f03\u65bc\u53f0\u5317\u3001\u65b0\u5317\uff0c\u53f0\u5357\u3001\u53f0\u4e2d\u3001\u9ad8\u96c4\u6703\u4fbf\u5b9c\u4e9b\uff09\u3001\u88fd\u4f5c\u65b9\u5f0f\uff08\u8207\u5b8c\u6574\u6cbb\u7642\u6642\u9593\u9700\uff11\u5929\u6216\uff11\u5468\u4ee5\u4e0a\u7684\u5dee\u7570\uff09 \u800c\u4f9d\u64da\u53f0\u5317\u5e02\u653f\u5e9c\u885b\u751f\u5c40\u8abf\u67e5\uff0c\u6bcf\u9846\u5168\u74f7\u51a0\u7684\u50f9\u683c\u7d042.2\u842c\u81f33.5\u842c\u5143\u5de6\u53f3\uff08\u5176\u4e0d\u542b\u8a3a\u5bdf\u8cbb\u7528\u3001\u7279\u6b8a\u5100\u5668\uff0c\u4e14\u4f9d\u64da\u5168\u74f7\u51a0\u4f7f\u7528\u6750\u6599\u3001\u88fd\u4f5c\u65b9\u5f0f\u4e0d\u540c\uff0c\u50f9\u683c\u4e5f\u6703\u6709\u6240\u5dee\u7570\uff09\u3002\u5168\u74f7\u7259\u51a0\/\u7259\u5957V.S\u50b3\u7d71\u74f7\u7259\u51a0\u50b3\u7d71\u74f7\u7259\u51a0\u5168\u74f7\u7259\u51a0\uff08\u7259\u5957\uff09\u6750\u8cea\u5916\u90e8\u74f7\u8cea+\u5167\u51a0\u91d1\u5c6c\u74f7\u584a\u5916\u89c0\u9078\u64c7\u5c11\uff0c\u8f03\u70ba\u6b7b\u767d\u53ef\u6839\u64da\u539f\u751f\u7259\u9f52\u8abf\u6574\u984f\u8272\u78e8\u640d\u6613\u78e8\u640d\u78e8\u640d\u7a0b\u5ea6\u8f03\u4f4e\u591a\u6578\u4f7f\u7528\u58fd\u547d\u53ef\u905410\u5e74\u4ee5\u4e0a\uff08\u78e8\u7259\u8005\u9808\u5e36\u591c\u9593\u4fdd\u8b77\u5957\uff09\u50f9\u683c\u8f03\u4f4e\u8f03\u9ad8\uff0820,000-30,000\u591a\u5143\uff09\u512a\u9ede\u50f9\u683c\u4fbf\u5b9c\u5916\u89c0\u81ea\u7136\u7f8e\u89c0\u5168\u74f7\u51a0\u7f3a\u9ede\u8207\u50b3\u7d71\u5047\u7259\u76f8\u6bd4\u5168\u74f7\u51a0\u6700\u5927\u7684\u7f3a\u9ede\u5c31\u662f\u50f9\u683c\u6703\u6bd4\u50b3\u7d71\u5047\u7259\u9ad8\u4e00\u4e9b\uff0c\u82e5\u662f\u8981\u5229\u7528\u5168\u74f7\u51a0\u505a\u7259\u9f52\u7f8e\u767d\u8cbc\u7247\uff0c\u50f9\u683c\u4e5f\u662f\u6703\u6bd4\u5176\u4ed6\u7f8e\u767d\u65b9\u6cd5\u9ad8\u4e00\u4e9b\uff0c\u4f46\u5168\u74f7\u51a0\u6700\u5927\u7684\u7279\u8272\uff0c\u5c31\u662f\u5805\u56fa\u4e14\u8010\u7528\uff0c\u8207\u539f\u751f\u7259\u9f52\u984f\u8272\u8f03\u70ba\u63a5\u8fd1\uff0c\u76f8\u5c0d\u4f86\u8aaa\u8f03\u70ba\u81ea\u7136\u3002\u5168\u74f7\u51a0\u7259\u5957\u6750\u8cea\u7a2e\u985e\u4ecb\u7d39\u6700\u5e38\u898b\u7684\u5168\u74f7\u7259\u51a0\u5047\u7259\u5206\u70ba\u4e8c\u77fd\u9178\u92f0\u548c\u4e8c\u6c27\u5316\u92ef\u5169\u7a2e\u3002\u25c6\u4e8c\u6c27\u5316\u92ef\u8207\u751f\u7269\u76f8\u5bb9\u6027\u9ad8\uff0c\u786c\u5ea6\u662f\u666e\u901a\u7259\u9f52\u76842\u30013\u500d\uff0c\u6240\u4ee5\u9069\u7528\u65bc\u5f8c\u7259\uff01\u4e0d\u904e\uff0c\u73fe\u5728\u7684\u4e8c\u6c27\u5316\u92ef\u6750\u8cea\u5df2\u7d93\u80fd\u505a\u5f97\u5f88\u6f02\u4eae\uff0c \u4e5f\u9069\u5408\u7528\u65bc\u524d\u7259\u3002 \u5c0d\u65bc\u6709\u78e8\u7259\u6216\u54ac\u786c\u7269\u7fd2\u6163\uff0c\u53c8\u60f3\u6ce8\u91cd\u7f8e\u89c0\u7684\u75c5\u60a3\u4e8c\u6c27\u5316\u92ef\u662f\u76f8\u7576\u7406\u60f3\u7684\u6750\u6599\u3002\u25c6\u4e8c\u77fd\u9178\u92f0\u5373\u70ba\u73bb\u7483\u9676\u74f7\uff0c\u6709\u8207\u771f\u7259\u5341\u5206\u76f8\u8fd1\u7684\u8272\u6fa4\uff0c\u900f\u5149\u6027\u4e5f\u5f88\u597d\uff0c\u4f46\u548c\u4e8c\u6c27\u5316\u92ef\u76f8\u8f03\u4e4b\u4e0b\uff0c\u786c\u5ea6\u65b9\u9762\u7565\u70ba\u905c\u8272\uff0c\u6240\u4ee5\u50c5\u9069\u7528\u65bc\u524d\u7259\u6216\u9580\u7259\u3002\u5168\u74f7\u7259\u51a0\/\u7259\u5957\u6750\u8cea\u4e8c\u6c27\u5316\u92ef\u4e8c\u77fd\u9178\u92f0\u5e38\u898b\u54c1\u724cCercon\u30013M Lava\u3001TDS\u3001Wieland\u3001VitaE-max\u3001Celtra Duo\u786c\u5ea6\u666e\u901a\u7259\u9f52\u76842\u30013\u500d\u666e\u901a\u9069\u7528\u5340\u57df\u5f8c\u7259\/\u524d\u7259\u524d\u7259\u50f9\u683c\u8f03\u9ad8\u8f03\u4f4e\u5168\u74f7\u51a0\u9069\u61c9\u75c7\u6709\u4ee5\u4e0b\u60c5\u6cc1\u8005\uff0c\u9069\u5408\u4f7f\u7528\u5168\u74f7\u7259\u51a0\/\u7259\u5957\uff081\uff09\u56b4\u91cd\u86c0\u7259\u8005\u56e0\u70ba\u86c0\u7259\u904e\u65bc\u56b4\u91cd\uff0c\u5c0e\u81f4\u7259\u9f52\u7522\u751f\u654f\u611f\uff0c\u4e14\u7259\u9f52\u7f3a\u640d\u904e\u5927\uff0c\u5149\u9760\u586b\u88dc\u7684\u65b9\u6cd5\u7121\u6cd5\u8b93\u7259\u9f52\u7a69\u56fa\uff0c\u4f46\u672a\u56b4\u91cd\u5230\u9700\u8981\u505a\u6839\u7ba1\u6cbb\u7642\u7684\u968e\u6bb5\uff0c\u5373\u53ef\u4f7f\u7528\u5168\u74f7\u51a0\u7259\u5957\uff0c\u907f\u514d\u7259\u9f52\u7e7c\u7e8c\u53d7\u640d\uff0c\u9020\u6210\u7259\u88c2\u7bc4\u570d\u64f4\u5927\u3002\uff082\uff09\u66fe\u63a5\u53d7\u6839\u7ba1\u6cbb\u7642\u8005\u300c\u6839\u7ba1\u6cbb\u7642\u300d\u4ea6\u5373\u300c\u62bd\u795e\u7d93\u300d\uff0c\u7531\u65bc\u7259\u9f52\u5728\u62bd\u904e\u795e\u7d93\u5f8c\uff0c\uff0c\u6703\u8b8a\u5f97\u8f03\u70ba\u8106\u5f31\uff0c\u6240\u4ee5\u70ba\u4e86\u4fdd\u8b77\u771f\u7259\uff0c\u907f\u514d\u54ac\u5230\u786c\u7269\u9020\u6210\u66f4\u5927\u7684\u7f3a\u640d\u6216\u7259\u6839\u65b7\u88c2\uff0c\u5efa\u8b70\u53ef\u4ee5\u505a\u5168\u74f7\u51a0\u7259\u5957\u4ee5\u7a69\u56fa\u7259\u9f52\u3002 \uff083\uff09\u56e0\u610f\u5916\u649e\u64ca\u800c\u4f7f\u7259\u9f52\u65b7\u88c2\u8005\u7259\u9f52\u70ba\u786c\u7d44\u7e54\uff0c\u6545\u7121\u6cd5\u81ea\u884c\u75ca\u7652\uff0c\u82e5\u65b7\u88c2\u7684\u9f52\u9762\u9762\u7a4d\u672a\u8d85\u904e\u4e09\u5206\u4e4b\u4e00\uff0c\u53ef\u80fd\u53ef\u4ee5\u75283D\u9f52\u96d5\u65b9\u5f0f\u586b\u88dc\uff0c\u82e5\u7259\u88c2\u7f3a\u640d\u7bc4\u570d\u904e\u5927\uff0c\u5247\u5efa\u8b70\u6839\u7ba1\u6cbb\u7642\u5f8c\uff0c\u505a\u5168\u74f7\u7259\u51a0\u6062\u5fa9\u54ac\u5408\u529b\u3002 \uff084\uff09\u56e0\u7f3a\u5c11\u7259\u9f52\u800c\u9700\u8981\u505a\u7259\u6a4b\u8005\u7f3a\u5c11\u7259\u9f52\u4e0d\u88dc\uff0c\u5bb9\u6613\u4f7f\u5176\u4ed6\u7259\u9f52\u9b06\u52d5\u4f4d\u79fb\uff0c\u82e5\u5728\u4e0d\u9078\u64c7\u690d\u7259\u7684\u60c5\u6cc1\u4e0b\uff0c\u5168\u74f7\u7259\u6a4b\u662f\u53e6\u4e00\u500b\u5f4c\u88dc\u7f3a\u5931\u7259\u9f52\u7684\u65b9\u6cd5\uff0c\u610f\u5373\u5229\u7528\u5168\u74f7\u7259\u51a0\u9032\u884c\u7259\u9f52\u91cd\u5efa\uff0c\u586b\u88dc\u53e3\u8154\u4e2d\u7f3a\u5931\u7684\u7259\u9f52\u3002\u56e0\u7f3a\u5c11\u7259\u9f52\u800c\u9700\u8981\u505a\u7259\u6a4b\u7684\u60a3\u8005\uff0c\u53ef\u4f7f\u7528\u5168\u74f7\u51a0\u7259\u5957\u6cbb\u7642\uff085\uff09\u539f\u6709\u5047\u7259\u6216\u7259\u6a4b\u5df2\u9b06\u52d5\u6216\u4e0d\u5bc6\u5408\u8005\u7259\u9f52\u54ac\u5408\u529b\u8207\u672c\u8eab\u7a69\u5b9a\u5ea6\u6709\u95dc\uff0c\u82e5\u662f\u5047\u7259\u9b06\u52d5\u6216\u7259\u6a4b\u5df2\u4e0d\u7a69\u56fa\u8005\uff0c\u5bb9\u6613\u9020\u6210\u4e8c\u6b21\u86c0\u7259\uff0c\u5efa\u8b70\u91cd\u65b0\u4ee5\u5168\u74f7\u51a0\u505a\u51fa\u66f4\u81ea\u7136\u7f8e\u89c0\u7684\u5047\u7259\uff0c\u4e14\u7121\u9808\u7b49\u5019\u6578\u65e5\uff0c\u6700\u5feb\u7576\u65e5\u5373\u53ef\u99ac\u4e0a\u88dd\u6234\u5047\u7259\u3002 \uff086\uff09\u539f\u6709\u586b\u88dc\u6a39\u8102\u6750\u6599\u8b8a\u8272\u6216\u4e0d\u5bc6\u5408\u8005 \u6a39\u8102\u6750\u6599\u56e0\u98f2\u98df\u7fd2\u6163\u95dc\u4fc2\u800c\u8b8a\u8272\uff0c\u4f7f\u5f97\u7259\u9f52\u7f8e\u89c0\u5927\u6253\u6298\u6263\uff0c\u82e5\u671f\u671b\u9032\u4e00\u6b65\u6539\u5584\u4e14\u907f\u514d\u767c\u751f\u4e8c\u6b21\u86c0\u7259\u7684\u60c5\u5f62\uff0cCAD-CAM-3D\u9f52\u96d5\u80fd\u73fe\u5834\u7814\u78e8\u4e26\u71d2\u88fd\u51fa\u6700\u7b26\u5408\u7684\u9f52\u8272\uff0c\u5728\u5bc6\u5408\u5ea6\u4e0a\u4e5f\u6709\u5f88\u597d\u7684\u6548\u679c\u3002\uff087\uff09\u4f7f\u7528\u9280\u7c89\u6750\u6599\u586b\u88dc\u8005\u8fd1\u5e7e\u5e74\u958b\u59cb\uff0c\u7531\u65bc\u6c11\u773e\u5c0d\u65bc\u9280\u7c89\u7684\u4f7f\u7528\u7565\u6709\u9867\u5fcc\uff0c\u4e5f\u56e0\u5176\u5bb9\u6613\u6c27\u5316\u767c\u9ed1...\u7b49\u554f\u984c\uff0c\u6f38\u6f38\u88ab\u74f7\u584a\u7b49\u6750\u6599\u53d6\u4ee3\uff0c\u82e5\u662f\u60a3\u8005\u5e0c\u671b\u80fd\u8abf\u6574\u9280\u7c89\u88dc\u9f52\u7684\u7f8e\u89c0\u5ea6\uff0cCAD-CAM-3D\u9f52\u96d5\u4e0d\u59a8\u80fd\u6210\u70ba\u4e00\u500b\u65b0\u9078\u9805\u3002\u258c\u5168\u74f7\u51a0\u7259\u5957\u6848\u4f8b\u53f0\u4e2d\u5168\u74f7\u51a0\u7f8e\u767d\u53ca\u8584\u74f7\u8cbc\u7247\u91cd\u5efa\u5168\u74f7\u51a0\u624b\u8853\u9650\u5236\u5982\u6709\u5176\u4ed6\u53e3\u8154\u75be\u75c5\u61c9\u5148\u884c\u6cbb\u7642\uff0c\u5f85\u6cbb\u7642\u5b8c\u6210\u5f8c\u518d\u9032\u884c\u5168\u74f7\u51a0\u624b\u8853\uff0c\u5426\u5247\u5c07\u5f71\u97ff\u6210\u6548\u4ee5\u53ca\u53e3\u8154\u5065\u5eb7\u3002\u82e5\u662f\u66fe\u7d93\u505a\u904e\u5176\u4ed6\u5047\u7259\u7684\u60a3\u8005\u4e5f\u9700\u8981\u544a\u77e5\u76f8\u95dc\u75c5\u53f2\uff0c\u4ee5\u4fbf\u8a55\u4f30\u5168\u74f7\u51a0\u624b\u8853\u76f8\u95dc\u7d30\u7bc0\u3002\u7576\u65e5\u6d41\u7a0b \u5168\u74f7\u51a0\u624b\u8853\u6d41\u7a0b\u4f9d\u500b\u4eba\u8a73\u7d30\u72c0\u6cc1\u800c\u5b9a\uff0c\u4ee5\u4e0b\u50c5\u4f9b\u53c3\u8003\u3002\u82e5\u5168\u74f7\u51a0\u624b\u8853\u9808\u9ebb\u9189\uff08TCI\uff09\uff0c\u5efa\u8b70\u7531\u89aa\u53cb\u966a\u540c\u524d\u5f80\u639b\u865f\u5019\u8a3a\u9032\u884c\u624b\u8853\u81f3\u4f11\u606f\u5340\u4f11\u606f\u8853\u5f8c\u5c45\u5bb6\u8b77\u7406\u6307\u5c0e\u9810\u7d04\u4e0b\u6b21\u56de\u8a3a\u6642\u9593\u8fd4\u5bb6\u4f11\u606f\uff08\u4e0d\u5b9c\u99d5\u99db\uff09\u5168\u74f7\u51a0\u624b\u8853\u5f8c\u6ce8\u610f\u4e8b\u9805\u907f\u514d\u5543\u54ac\u5805\u786c\u7684\u98df\u7269\uff08\u5927\u9aa8\u3001\u5805\u679c\u7b49\uff09\u3002\u8acb\u52ff\u5438\u83f8\u3001\u56bc\u6642\u6ab3\u6994\uff0c\u4ee5\u7dad\u8b77\u53e3\u8154\u5065\u5eb7\u3002\u5982\u6709\u591c\u9593\u78e8\u7259\u7fd2\u6163\uff0c\u8acb\u914d\u6234\u8b77\u5957\u4ee5\u907f\u514d\u7834\u88c2\u3002\u5168\u74f7\u51a0\u5e38\u898b\u554f\u984cQ\uff1a\u5168\u74f7\u51a0\u7259\u5957\u58fd\u547d\u6709\u591a\u9577\uff1f\u53ef\u4ee5\u7528\u4e00\u8f29\u5b50\u55ce\uff1fA\uff1a\u6b63\u78ba\u7684\u6e05\u6f54\u65b9\u6cd5\u53ca\u826f\u597d\u7684\u53e3\u8154\u885b\u751f\u7fd2\u6163\uff0c\u5168\u74f7\u51a0\u662f\u53ef\u4ee5\u9577\u671f\u4f7f\u7528\uff08\u591a\u6578\u5168\u74f7\u51a0\u58fd\u547d\u53ef\u8d85\u904e10\u5e74\uff09\uff0c\u800c\u4e14\u8a3a\u6240\u88fd\u4f5c\u7684\u5168\u74f7\u51a0\u4e5f\u6709\u63d0\u4f9b\u4fdd\u56fa\uff0c\u53ea\u8981\u7dad\u8b77\u597d\u53e3\u8154\u5065\u5eb7\u4e26\u4e0d\u9700\u8981\u904e\u5ea6\u64d4\u5fc3\uff0c\u4e5f\u5efa\u8b70\u6bcf\u534a\u5e74\u9032\u884c\u53e3\u8154\u6aa2\u67e5\u6642\u78ba\u8a8d\u5168\u74f7\u51a0\u7684\u72c0\u6cc1\u3002Q\uff1a\u5168\u74f7\u51a0\u7684\u6750\u8cea\u662f\u4ec0\u9ebc\uff1fA\uff1a\u5168\u74f7\u51a0\u7684\u7a2e\u985e\u5206\u70ba\u8a31\u591a\u7a2e\uff0c\u50f9\u9322\u4e5f\u6703\u6709\u6240\u4e0d\u540c\u3002\u4e3b\u8981\u6709\u73bb\u7483\u9676\u74f7\uff08\u5373\u4e8c\u77fd\u9178\u92f0\uff09\u4ee5\u53ca\u4e8c\u6c27\u5316\u92ef\uff0c\u76f8\u8f03\u65bc\u50b3\u7d71\u91d1\u5c6c\u74f7\u7259\uff0c\u6709\u908a\u7de3\u8f03\u5bc6\u5408\u3001\u984f\u8272\u81ea\u7136\u3001\u4eff\u771f\u5ea6\u9ad8\u53ca\u9ad8\u5f37\u5ea6\u7b49\u512a\u9ede\u3002Q\uff1a\u55a8\u7c92\u6676\u7259\u91ab\u7684\u5168\u74f7\u51a0\u6cbb\u7642\u6709\u4ec0\u9ebc\u512a\u9ede\uff1fA\uff1a\u55a8\u7c92\u6676\u4f7f\u7528CAD\uff0fCAM\u79d1\u6280\uff0c\u80fd\u5927\u5e45\u6e1b\u77ed\u5168\u74f7\u51a0\u5047\u7259\u9ad4\u88fd\u4f5c\u6642\u9593\uff0c\u540c\u6642\u642d\u914d3D\u53e3\u5167\u651d\u5f71\u3001CAD\u8a2d\u8a08\u3001CAM\u88fd\u4f5c\uff0c\u5b8c\u6210\u6700\u7cbe\u6e96\u81ea\u7136\u7684\u5047\u7259\u88fd\u4f5c\u3002\uff08\u5ef6\u4f38\u95b1\u8b80\uff1aCAD-CAM\u6578\u4f4d\u9f52\u96d5\uff09Q\uff1a\u5168\u74f7\u51a0\u50f9\u683c\u591a\u5c11\uff1fA\uff1a\u5168\u74f7\u51a0\u7531\u65bc\u4e0d\u5c6c\u65bc\u5065\u4fdd\u7d66\u4ed8\u7684\u7bc4\u570d\uff0c\u9700\u8981\u9032\u884c\u81ea\u8cbb\uff0c\u5168\u74f7\u51a0\u50f9\u683c\u7d04\u843d\u572820,000-30,000\u591a\u5143\u3002\u800c\u5176\u4ed6\u7684\u53e3\u8154\u624b\u8853\u5247\u9700\u8981\u6309\u7167\u5065\u4fdd\u7d66\u4ed8\u898f\u5b9a\u8207\u5426\u4f86\u8655\u7406\uff0c\u56e0\u6b64\u5168\u74f7\u51a0\u50f9\u683c\u4e26\u4e0d\u662f\u6bcf\u500b\u4eba\u90fd\u4e00\u6a23\u7684\uff0c\u6240\u4ee5\u53ef\u4ee5\u8207\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u91ab\u5e2b\u9032\u884c\u8a73\u7d30\u8aee\u8a62\u4e26\u8a55\u4f30\u5c08\u5c6c\u7684\u7642\u7a0b\u8207\u50f9\u683c\u3002Q\uff1a\u5168\u74f7\u51a0\u50f9\u683c\u6703\u6709\u5dee\u7570\u55ce\uff1fA\uff1a\u6839\u64da\u5404\u500b\u8a3a\u6240\u5370\u819c\u6750\u6599\u3001\u74f7\u584a\u54c1\u724c\u7b49\u56e0\u7d20\uff0c\u6703\u9020\u6210\u540c\u6a23\u7684\u624b\u8853\u5b58\u5728\u8457\u5168\u74f7\u51a0\u50f9\u683c\u5dee\u7570\uff0c\u56e0\u6b64\u5efa\u8b70\u60a8\u53ef\u89aa\u81ea\u5230\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u8aee\u8a62\u5168\u74f7\u51a0\u76f8\u95dc\u7642\u7a0b\uff0c\u900f\u904e\u8a73\u7d30\u8aaa\u660e\u5373\u53ef\u4e86\u89e3\u9069\u5408\u81ea\u5df1\u7684\u7642\u7a0b\u8cbb\u7528.....\u7b49\u7d30\u7bc0\u3002Q\uff1a\u5168\u74f7\u51a0\u5c31\u662f\u5047\u7259\u7259\u5957\u55ce\uff1fA\uff1a\u662f\u7684\uff0c\u5168\u74f7\u51a0\u8207\u50b3\u7d71\u91d1\u5c6c\u7259\u51a0\u7b49\u7686\u5c6c\u65bc\u5047\u7259\u7259\u5957\u7684\u7bc4\u7587\uff0c\u4f46\u4e26\u4e0d\u662f\u4e00\u822c\u5370\u8c61\u4e2d\u8001\u4eba\u4f7f\u7528\u7684\u90a3\u7a2e\u6d3b\u52d5\u5047\u7259\uff0c\u4f7f\u7528\u4e0a\u4e5f\u53ea\u9700\u8981\u6ce8\u610f\u53e3\u8154\u4fdd\u5065\u5373\u53ef\u6b63\u5e38\u4f7f\u7528\uff0c\u5168\u74f7\u51a0\u7259\u5957\u4e26\u4e0d\u6703\u9020\u6210\u751f\u6d3b\u4e0d\u4fbf\u3002\r\n\", \r\n\t\"url\" : \"https:\/\/www.shining-dc.com.tw\/all-ceramic-crown\/\", \r\n\t\"publisher\" : { \r\n\t\"@type\" : \"Organization\", \r\n\t\"logo\" : \"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Group-660.png\", \r\n\t\"name\" : \"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012022\u6750\u8cea\uff06\u58fd\u547d\" \r\n\t} \r\n\t} \r\n\t<\/script>\r\n<script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"http:\/\/schema.org\",\r\n  \"@type\": \"Product\",\r\n  \"name\": \"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012022\u6750\u8cea\uff06\u58fd\u547d\",\r\n\"image\": \"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Mask-Group-35.jpg\",\r\n\r\n\"description\": \"\u4f60\u77e5\u9053\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\u55ce\uff1f\u9084\u5728\u64d4\u5fc3\u5168\u74f7\u51a0\u7259\u5957\u7684\u50f9\u683c\u5f88\u8cb4\u55ce\uff1f\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u544a\u8a34\u4f60\u50b3\u7d71\u548c\u5168\u74f7\u51a0\u7259\u5957\u5047\u7259\u6709\u4ec0\u9ebc\u4e0d\u540c\uff0c\u4ee5\u53ca\u5168\u74f7\u51a0\u7259\u5957\u50f9\u683c\uff0820,000-30,000\u591a\u5143\uff09\u548c\u6750\u8cea\u7684\u5dee\u7570\u4ecb\u7d39\uff0c\u7d66\u60a8\u6700\u5c08\u696d\u7684\u5168\u74f7\u51a0\u7f8e\u767d\u670d\u52d9\u3002\",\r\n  \"offers\": {\r\n    \"@type\": \"Offer\",\r\n    \"price\": \"20000.00\",\r\n     \"offerCount\": \"5\",\r\n          \"lowPrice\": \"20000.00\",\r\n          \"highPrice\": \"39000.00\",\r\n    \"priceCurrency\": \"TWD\",\r\n    \"url\": \"https:\/\/www.shining-dc.com.tw\/all-ceramic-crown\/\"\r\n  },\r\n     \r\n  \"startDate\": \"2021-10-25T12:30\"\r\n}\r\n<\/script>\r\n\r\n\r\n\t<script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"https:\/\/schema.org\",\r\n  \"@type\": \"Article\",\r\n  \"mainEntityOfPage\": {\r\n    \"@type\": \"WebPage\",\r\n    \"@id\": \"https:\/\/www.shining-dc.com.tw\/all-ceramic-crown\/\"\r\n  },\r\n  \"headline\": \"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012022\u6750\u8cea\uff06\u58fd\u547d\",\r\n  \"description\": \"\u4f60\u77e5\u9053\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\u55ce\uff1f\u9084\u5728\u64d4\u5fc3\u5168\u74f7\u51a0\u7259\u5957\u7684\u50f9\u683c\u5f88\u8cb4\u55ce\uff1f\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u544a\u8a34\u4f60\u50b3\u7d71\u548c\u5168\u74f7\u51a0\u7259\u5957\u5047\u7259\u6709\u4ec0\u9ebc\u4e0d\u540c\uff0c\u4ee5\u53ca\u5168\u74f7\u51a0\u7259\u5957\u50f9\u683c\uff0820,000-30,000\u591a\u5143\uff09\u548c\u6750\u8cea\u7684\u5dee\u7570\u4ecb\u7d39\uff0c\u7d66\u60a8\u6700\u5c08\u696d\u7684\u5168\u74f7\u51a0\u7f8e\u767d\u670d\u52d9\u3002\",\r\n  \"image\": \"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Mask-Group-35.jpg\",  \r\n  \"author\": {\r\n    \"@type\": \"Organization\",\r\n    \"name\": \"\u674e\u6606\u7e09\u91ab\u5e2b\"\r\n  },  \r\n  \"publisher\": {\r\n    \"@type\": \"Organization\",\r\n    \"name\": \"\u674e\u6606\u7e09\u91ab\u5e2b\",\r\n    \"logo\": {\r\n      \"@type\": \"ImageObject\",\r\n      \"url\": \"https:\/\/www.shining-dc.com.tw\/team-introduction\/\"\r\n    }\r\n  },\r\n  \"datePublished\": \"2019-12-06\",\r\n  \"dateModified\": \"2020-08-05\"\r\n}\r\n<\/script>\r\n\r\n  <script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"https:\/\/schema.org\",\r\n  \"@type\": \"FAQPage\",\r\n  \"mainEntity\": [{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"\u4ec0\u9ebc\u662f\u5168\u74f7\u51a0?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"\u76f8\u8f03\u65bc\u50b3\u7d71\u7684\u7259\u51a0\uff0c\u5168\u74f7\u51a0\u7684\u6750\u8cea\u7531\u5167\u800c\u5916\u90fd\u662f\u4ee5\u300c\u74f7\u584a\u300d\u70ba\u6750\u6599\u6253\u9020\u800c\u6210\u7684\u5168\u74f7\u51a0\u7259\u5957\uff0c\u4e0d\u542b\u4efb\u4f55\u91d1\u5c6c\u6210\u5206\uff0c\u6750\u6599\u8207\u4eba\u9ad4\u7684\u76f8\u5bb9\u6027\u8f03\u4f73\uff0c\u6c92\u6709\u81f4\u764c\u7591\u616e\uff0c\u4e0d\u5bb9\u6613\u6709\u767c\u708e\u6216\u904e\u654f\u73fe\u8c61\uff0c\u4e5f\u4e0d\u6703\u4f7f\u7259\u9f66\u908a\u7de3\u8b8a\u8272\uff0c\u6240\u4ee5\u4e5f\u6709\u4e0d\u5c11\u4eba\u5c07\u5168\u74f7\u51a0\u7259\u5957\u4f5c\u70ba\u7f8e\u767d\u7684\u4e00\u7a2e\u9078\u64c7\"}\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"\u5168\u74f7\u51a0\u624b\u8853\u6709\u4ec0\u9ebc\u9650\u5236\uff1f\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"\u5982\u6709\u5176\u4ed6\u53e3\u8154\u75be\u75c5\u61c9\u5148\u884c\u6cbb\u7642\uff0c\u5f85\u6cbb\u7642\u5b8c\u6210\u5f8c\u518d\u9032\u884c\u5168\u74f7\u51a0\u624b\u8853\uff0c\u5426\u5247\u5c07\u5f71\u97ff\u6210\u6548\u4ee5\u53ca\u53e3\u8154\u5065\u5eb7\u3002\u82e5\u662f\u66fe\u7d93\u505a\u904e\u5176\u4ed6\u5047\u7259\u7684\u60a3\u8005\u4e5f\u9700\u8981\u544a\u77e5\u76f8\u95dc\u75c5\u53f2\uff0c\u4ee5\u4fbf\u8a55\u4f30\u5168\u74f7\u51a0\u624b\u8853\u76f8\u95dc\u7d30\u7bc0\u3002\" }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"\u5168\u74f7\u51a0\u7259\u5957\u53ef\u4ee5\u7528\u4e00\u8f29\u5b50\u55ce\uff1f\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"\u6b63\u78ba\u7684\u6e05\u6f54\u65b9\u6cd5\u53ca\u826f\u597d\u7684\u53e3\u8154\u885b\u751f\u7fd2\u6163\uff0c\u5168\u74f7\u51a0\u662f\u53ef\u4ee5\u9577\u671f\u4f7f\u7528\u800c\u4e14\u8a3a\u6240\u88fd\u4f5c\u7684\u5168\u74f7\u51a0\u4e5f\u6709\u63d0\u4f9b\u4fdd\u56fa\uff0c\u53ea\u8981\u7dad\u8b77\u597d\u53e3\u8154\u5065\u5eb7\u4e26\u4e0d\u9700\u8981\u904e\u5ea6\u64d4\u5fc3\uff0c\u4e5f\u5efa\u8b70\u6bcf\u534a\u5e74\u9032\u884c\u53e3\u8154\u6aa2\u67e5\u6642\u78ba\u8a8d\u5168\u74f7\u51a0\u7684\u72c0\u6cc1\u3002\" }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"\u5168\u74f7\u51a0\u7684\u6750\u8cea\u662f\u4ec0\u9ebc\uff1f\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"\u5168\u74f7\u51a0\u5047\u7259\u7684\u7a2e\u985e\u5206\u70ba\u8a31\u591a\u7a2e\uff0c\u50f9\u9322\u4e5f\u6703\u6709\u6240\u4e0d\u540c\u3002\u4e3b\u8981\u6709\u73bb\u7483\u9676\u74f7\uff08\u5373\u4e8c\u77fd\u9178\u92f0\uff09\u4ee5\u53ca\u4e8c\u6c27\u5316\u92ef\uff0c\u76f8\u8f03\u65bc\u50b3\u7d71\u91d1\u5c6c\u74f7\u7259\uff0c\u6709\u908a\u7de3\u8f03\u5bc6\u5408\u3001\u984f\u8272\u81ea\u7136\u3001\u4eff\u771f\u5ea6\u9ad8\u53ca\u9ad8\u5f37\u5ea6\u7b49\u512a\u9ede\u3002\"}\r\n  },\r\n  {\r\n    \"@type\": \"Question\",\r\n    \"name\": \"\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u7684\u5168\u74f7\u51a0\u5047\u7259\u6cbb\u7642\u6709\u4ec0\u9ebc\u512a\u9ede\uff1f\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"\u53f0\u4e2d\u55a8\u7c92\u6676\u4f7f\u7528CAD\uff0fCAM\u79d1\u6280\uff0c\u80fd\u5927\u5e45\u6e1b\u77ed\u5168\u74f7\u51a0\u5047\u7259\u9ad4\u88fd\u4f5c\u6642\u9593\uff0c\u540c\u6642\u642d\u914d3D\u53e3\u5167\u651d\u5f71\uff0cCAD\u8a2d\u8a08\uff0cCAM\u88fd\u4f5c\uff0c\u5b8c\u6210\u6700\u7cbe\u6e96\u81ea\u7136\u7684\u5047\u7259\u88fd\u4f5c\u3002\" }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\u591a\u5c11\uff1f\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"\u5168\u74f7\u51a0\u7531\u65bc\u4e0d\u5c6c\u65bc\u5065\u4fdd\u7d66\u4ed8\u7684\u7bc4\u570d\uff0c\u9700\u8981\u9032\u884c\u81ea\u8cbb\uff0c\u5168\u74f7\u51a0\u50f9\u683c\u7d04\u843d\u572820,000-30,000\u591a\u5143\u3002\u800c\u5176\u4ed6\u7684\u53e3\u8154\u624b\u8853\u5247\u9700\u8981\u6309\u7167\u5065\u4fdd\u7d66\u4ed8\u898f\u5b9a\u8207\u5426\u4f86\u8655\u7406\uff0c\u56e0\u6b64\u5168\u74f7\u51a0\u7684\u50f9\u683c\u4e26\u4e0d\u662f\u6bcf\u500b\u4eba\u90fd\u4e00\u6a23\u7684\uff0c\u6240\u4ee5\u53ef\u4ee5\u8207\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u91ab\u5e2b\u9032\u884c\u8a73\u7d30\u8aee\u8a62\u4e26\u8a55\u4f30\u5c08\u5c6c\u7684\u7642\u7a0b\u8207\u50f9\u683c\u3002\" }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"\u5168\u74f7\u51a0\u5c31\u662f\u5047\u7259\u55ce\uff1f\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"\u662f\u7684\uff0c\u5168\u74f7\u51a0\u8207\u91d1\u5c6c\u51a0\u7b49\u7686\u5c6c\u65bc\u5047\u7259\u7259\u5957\u7684\u7bc4\u7587\uff0c\u4f46\u4e26\u4e0d\u662f\u4e00\u822c\u5370\u8c61\u4e2d\u8001\u4eba\u4f7f\u7528\u7684\u90a3\u7a2e\u6d3b\u52d5\u5047\u7259\uff0c\u4f7f\u7528\u4e0a\u4e5f\u53ea\u9700\u8981\u6ce8\u610f\u53e3\u8154\u4fdd\u5065\u5373\u53ef\u6b63\u5e38\u4f7f\u7528\uff0c\u5168\u74f7\u51a0\u7259\u5957\u4e26\u4e0d\u6703\u9020\u6210\u751f\u6d3b\u4e0d\u4fbf\u3002\"  }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"\u5168\u74f7\u51a0\u5047\u7259\u6703\u6709\u50f9\u683c\u5dee\u7570\u55ce\uff1f\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"\u6839\u64da\u5404\u500b\u8a3a\u6240\u5370\u819c\u6750\u6599\u3001\u74f7\u584a\u54c1\u724c\u7b49\u56e0\u7d20\uff0c\u6703\u9020\u6210\u540c\u6a23\u7684\u5168\u74f7\u51a0\u5047\u7259\u5b58\u5728\u8457\u50f9\u683c\u5dee\u7570\uff0c\u56e0\u6b64\u5efa\u8b70\u60a8\u53ef\u89aa\u81ea\u5230\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u8aee\u8a62\u5168\u74f7\u51a0\u76f8\u95dc\u7642\u7a0b\uff0c\u900f\u904e\u8a73\u7d30\u8aaa\u660e\u5373\u53ef\u4e86\u89e3\u9069\u5408\u81ea\u5df1\u7684\u7642\u7a0b\u8cbb\u7528\u7b49\u7d30\u7bc0\u3002\"\r\n    }\r\n  }]\r\n}\r\n<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef8dccd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ef8dccd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9bfbf0f\" data-id=\"9bfbf0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e9b5953 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9b5953\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3160588\" data-id=\"3160588\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43dba87 elementor-widget elementor-widget-text-editor\" data-id=\"43dba87\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u6839\u7ba1\u6cbb\u7642\u5f8c\u306e\u6b6f\u306e\u6b6f\u830e\u5468\u8fba\u306e\u9ed2\u305a\u307f\u306b\u60a9\u3093\u3067\u3044\u307e\u305b\u3093\u304b\uff1f<br \/>\u3042\u308b\u3044\u306f\u3001\u6b6f\u306e\u89d2\u304c\u6b20\u3051\u3066\u3057\u307e\u3063\u3066\u60a9\u3093\u3067\u3044\u307e\u305b\u3093\u304b\uff1f<br \/>\u8fd1\u5e74\u3001\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3092\u4f7f\u7528\u3057\u305f\u6b6f\u306e\u4fee\u5fa9\u304c\u5e74\u3005\u5897\u3048\u3066\u3044\u307e\u3059<\/p><p>\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3068\u306f\u4e00\u4f53\u4f55\u3067\u3057\u3087\u3046\u304b\uff1f<br \/>\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306f\u300c\u7fa9\u6b6f\u3001\u6b6f\u306e\u88ab\u305b\uff08\u6b6f\u51a0\u88dc\u7db4\u7269\uff09\u3001\u30e9\u30df\u30cd\u30fc\u30c8\u3079\u30cb\u30a2\u300d\u3068\u3057\u3066\u3082\u4f7f\u7528\u3067\u304d\u308b\u3068\u8a00\u308f\u308c\u3066\u3044\u307e\u3059\u3002<br \/>\u3055\u3042\u3001\u8a73\u3057\u304f\u898b\u3066\u3044\u304d\u307e\u3057\u3087\u3046\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1d328de elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d328de\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-20fcbc1\" data-id=\"20fcbc1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78ebb48 elementor-widget elementor-widget-text-editor\" data-id=\"78ebb48\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"p1\"><span class=\"s1\">\u6839\u7ba1\u6cbb\u7642\u5f8c\u306e\u6b6f\u306e\u6b6f\u830e\u5468\u8fba\u306e\u9ed2\u305a\u307f\u306b\u60a9\u3093\u3067\u3044\u307e\u305b\u3093\u304b\uff1f\u3042\u308b\u3044\u306f\u3001\u6b6f\u306e\u89d2\u304c\u6b20\u3051\u3066\u3057\u307e\u3063\u3066\u60a9\u3093\u3067\u3044\u307e\u305b\u3093\u304b\uff1f\u8fd1\u5e74\u3001\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3092\u4f7f\u7528\u3057\u305f\u6b6f\u306e\u4fee\u5fa9\u304c\u5e74\u3005\u5897\u3048\u3066\u3044\u307e\u3059<\/span><\/p><p class=\"p1\"><span class=\"s1\">\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3068\u306f\u4e00\u4f53\u4f55\u3067\u3057\u3087\u3046\u304b\uff1f\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306f\u300c\u7fa9\u6b6f\u3001\u6b6f\u306e\u88ab\u305b\uff08\u6b6f\u51a0\u88dc\u7db4\u7269\uff09\u3001\u30e9\u30df\u30cd\u30fc\u30c8\u3079\u30cb\u30a2\u300d\u3068\u3057\u3066\u3082\u4f7f\u7528\u3067\u304d\u308b\u3068\u8a00\u308f\u308c\u3066\u3044\u307e\u3059\u3002\u3055\u3042\u3001\u8a73\u3057\u304f\u898b\u3066\u3044\u304d\u307e\u3057\u3087\u3046\u3002<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94b6da2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94b6da2\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01f9367\" data-id=\"01f9367\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8996e43 elementor-widget elementor-widget-text-editor\" data-id=\"8996e43\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u3010\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3068\u306f\uff1f\u3011\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ed2874 elementor-section-full_width elementor-section-content-middle elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"5ed2874\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c96975c\" data-id=\"c96975c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b70b61 elementor-widget elementor-widget-text-editor\" data-id=\"9b70b61\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u5f93\u6765\u306e\u30af\u30e9\u30a6\u30f3\u306f\u300c\u5916\u5074\u304c\u30bb\u30e9\u30df\u30c3\u30af\u3067\u3001\u5185\u5074\u304c\u91d1\u5c5e\u300d\u3067\u3057\u305f\u304c\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306f\u3001\u300c\u3059\u3079\u3066\u304c\u30bb\u30e9\u30df\u30c3\u30af\u300d\u3067\u3059\u3002\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\uff15\u5927\u30e1\u30ea\u30c3\u30c8\u306f\u3001\u91d1\u5c5e\u3092\u542b\u307e\u306a\u3044\u3001\u4eba\u4f53\u3068\u306e\u89aa\u548c\u6027\u304c\u9ad8\u3044\u3001\u767a\u304c\u3093\u306e\u61f8\u5ff5\u304c\u306a\u3044\u3001\u708e\u75c7\u3084\u30a2\u30ec\u30eb\u30ae\u30fc\u3092\u8d77\u3053\u3057\u306b\u304f\u3044\u3001\u6b6f\u8089\u306e\u5468\u308a\u304c\u5909\u8272\u3057\u306a\u3044\u70b9\u3067\u3059\u3002\n\n\u307e\u305f\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u8272\u306f\u3001\u81ea\u7136\u3067\u672c\u7269\u306e\u6b6f\u306b\u8fd1\u3044\u305f\u3081\u3001\u30db\u30ef\u30a4\u30c8\u30cb\u30f3\u30b0\u306e\u9078\u629e\u80a2\u3068\u3057\u3066\u30e9\u30df\u30cd\u30fc\u30c8\u3079\u30cb\u30a2\u3092\u4f7f\u7528\u3059\u308b\u65b9\u3082\u591a\u304f\u3044\u3089\u3063\u3057\u3083\u3044\u307e\u3059\u3002\u25b8( \u3053\u3061\u3089\u3092\u3054\u89a7\u304f\u3060\u3055\u3044\n<a href=\"\/\u7259\u9f52\u7f8e\u767d\"><span style=\"color: #6ca45b;\">\u305d\u306e\u4ed6\u306e\u30db\u30ef\u30a4\u30c8\u30cb\u30f3\u30b0\u306b\u3064\u3044\u3066\u8a73\u3057\u304f\u77e5\u308a\u305f\u3044\u65b9\u306f<\/span><\/a> )\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68ed567\" data-id=\"68ed567\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1642ea elementor-widget elementor-widget-image\" data-id=\"a1642ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"610\" height=\"508\" src=\"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Group-690-2.png\" class=\"attachment-large size-large wp-image-822\" alt=\"\" srcset=\"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Group-690-2.png 610w, https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Group-690-2-300x250.png 300w\" sizes=\"(max-width: 610px) 100vw, 610px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec65216 elementor-section-full_width elementor-section-content-middle elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"ec65216\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c7a4558\" data-id=\"c7a4558\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-204fea1 elementor-widget elementor-widget-text-editor\" data-id=\"204fea1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u5f93\u6765\u306e\u30af\u30e9\u30a6\u30f3\u306f\u300c\u5916\u5074\u304c\u30bb\u30e9\u30df\u30c3\u30af\u3067\u3001\u5185\u5074\u304c\u91d1\u5c5e\u300d\u3067\u3057\u305f\u304c\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306f\u3001\u300c\u3059\u3079\u3066\u304c\u30bb\u30e9\u30df\u30c3\u30af\u300d\u3067\u3059\u3002\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\uff15\u5927\u30e1\u30ea\u30c3\u30c8\u306f\u3001\u91d1\u5c5e\u3092\u542b\u307e\u306a\u3044\u3001\u4eba\u4f53\u3068\u306e\u89aa\u548c\u6027\u304c\u9ad8\u3044\u3001\u767a\u304c\u3093\u306e\u61f8\u5ff5\u304c\u306a\u3044\u3001\u708e\u75c7\u3084\u30a2\u30ec\u30eb\u30ae\u30fc\u3092\u8d77\u3053\u3057\u306b\u304f\u3044\u3001\u6b6f\u8089\u306e\u5468\u308a\u304c\u5909\u8272\u3057\u306a\u3044\u70b9\u3067\u3059\u3002<\/p><p>\u307e\u305f\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u8272\u306f\u3001\u81ea\u7136\u3067\u672c\u7269\u306e\u6b6f\u306b\u8fd1\u3044\u305f\u3081\u3001\u30db\u30ef\u30a4\u30c8\u30cb\u30f3\u30b0\u306e\u9078\u629e\u80a2\u3068\u3057\u3066\u30e9\u30df\u30cd\u30fc\u30c8\u3079\u30cb\u30a2\u3092\u4f7f\u7528\u3059\u308b\u65b9\u3082\u591a\u304f\u3044\u3089\u3063\u3057\u3083\u3044\u307e\u3059\u3002\u25b8( \u3053\u3061\u3089\u3092\u3054\u89a7\u304f\u3060\u3055\u3044<br \/><a href=\"\/\u7259\u9f52\u7f8e\u767d\"><span style=\"color: #6ca45b;\">\u305d\u306e\u4ed6\u306e\u30db\u30ef\u30a4\u30c8\u30cb\u30f3\u30b0\u306b\u3064\u3044\u3066\u8a73\u3057\u304f\u77e5\u308a\u305f\u3044\u65b9\u306f<\/span><\/a> )<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d50f5e6\" data-id=\"d50f5e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b9345f elementor-widget elementor-widget-image\" data-id=\"0b9345f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"610\" height=\"508\" src=\"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Group-690-2.png\" class=\"attachment-large size-large wp-image-822\" alt=\"\" srcset=\"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Group-690-2.png 610w, https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Group-690-2-300x250.png 300w\" sizes=\"(max-width: 610px) 100vw, 610px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-840d4fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"840d4fa\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b448090\" data-id=\"b448090\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63b450a elementor-widget elementor-widget-text-editor\" data-id=\"63b450a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u3010\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3068\u5f93\u6765\u306e\u30af\u30e9\u30a6\u30f3\u306e\u6bd4\u8f03\u3011\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ec36f9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1ec36f9\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9e18ddc\" data-id=\"9e18ddc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-086879f elementor-widget elementor-widget-image\" data-id=\"086879f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"547\" height=\"400\" src=\"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Mask-Group-35.jpg\" class=\"attachment-large size-large wp-image-832\" alt=\"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012022\u6750\u8cea\uff06\u58fd\u547d\" srcset=\"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Mask-Group-35.jpg 547w, https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Mask-Group-35-300x219.jpg 300w\" sizes=\"(max-width: 547px) 100vw, 547px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0658241 elementor-widget elementor-widget-text-editor\" data-id=\"0658241\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u5f93\u6765\u306e\u30af\u30e9\u30a6\u30f3\u3068\u6bd4\u8f03\u3057\u3066\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u6700\u5927\u306e\u6b20\u70b9\u306f\u3001\u4fa1\u683c\u304c\u5f93\u6765\u306e\u7fa9\u6b6f\u3088\u308a\u9ad8\u3081\u3067\u3042\u308b\u3053\u3068\u3067\u3059\u3002\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u3067\u30e9\u30df\u30cd\u30fc\u30c8\u3079\u30cb\u30a2\u3092\u88fd\u4f5c\u3059\u308b\u5834\u5408\u3001\u305d\u306e\u4fa1\u683c\u3082\u4ed6\u306e\u30db\u30ef\u30a4\u30c8\u30cb\u30f3\u30b0\u65b9\u6cd5\u3088\u308a\u9ad8\u3081\u306b\u306a\u308a\u307e\u3059\u304c\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306b\u306f\u3001\u305d\u306e\u6700\u5927\u306e\u7279\u8272\u3067\u3042\u308b\u3001\u4e08\u592b\u3055\u3068\u8010\u4e45\u6027\u3001\u305d\u3057\u3066\u4e8c\u6b21\u7684\u306a\u7740\u8272\u306e\u554f\u984c\u304c\u306a\u3044\u3001\u5143\u306e\u6b6f\u306e\u8272\u306b\u307b\u3068\u3093\u3069\u8fd1\u304f\u3001\u81ea\u7136\u3067\u7f8e\u3057\u3044\u4ed5\u4e0a\u304c\u308a\u306b\u306a\u308b\u3068\u3044\u3046\u5927\u304d\u306a\u30e1\u30ea\u30c3\u30c8\u304c\u3042\u308a\u307e\u3059\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-12c8693\" data-id=\"12c8693\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6e68c1 elementor-widget elementor-widget-jet-table\" data-id=\"e6e68c1\" data-element_type=\"widget\" data-widget_type=\"jet-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-table jet-elements\">\n\t\t<div class=\"jet-table-wrapper jet-table-responsive-mobile\">\n\t\t\t<table class=\"jet-table jet-table--fa5-compat\">\n\t\t\t\t<thead class=\"jet-table__head\"><tr class=\"jet-table__head-row\"><th class=\"jet-table__cell elementor-repeater-item-7c5a22a jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-65d731f jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u5f93\u6765\u306e\u30af\u30e9\u30a6\u30f3<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-18a3ee0 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3<\/div><\/div><\/div><\/th><\/tr><\/thead>\n\t\t\t\t\t\t\t\t<tbody class=\"jet-table__body\"><tr class=\"jet-table__body-row elementor-repeater-item-e0452f3\"><td class=\"jet-table__cell elementor-repeater-item-200fbbb jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u7d20\u6750<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-ad3f62d jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u5916\u5074\u306f\u30bb\u30e9\u30df\u30c3\u30af\u3001\u5185\u5074\u306f\u91d1\u5c5e<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-14e0553 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u30bb\u30e9\u30df\u30c3\u30af<\/div><\/div><\/div><\/td><\/tr><tr class=\"jet-table__body-row elementor-repeater-item-4b3881d\"><td class=\"jet-table__cell elementor-repeater-item-a2f1d2c jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u5916\u89b3<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-34bde1b jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u9078\u629e\u80a2\u304c\u5c11\u306a\u3044\u3001\u8272\u306f\u767d<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-0dac353 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u5143\u306e\u6b6f\u306e\u8272\u306b\u5408\u308f\u305b\u3066\u8272\u3092\u8abf\u6574\u3067\u304d\u308b<\/div><\/div><\/div><\/td><\/tr><tr class=\"jet-table__body-row elementor-repeater-item-c7cbf94\"><td class=\"jet-table__cell elementor-repeater-item-fd9a9e7 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u78e8\u8017<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-431190f jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u78e8\u8017\u3057\u3084\u3059\u3044<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-209ddd3 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u78e8\u8017\u304c\u5c11\u306a\u3044<br>\n\u591a\u304f\u306e\u5834\u5408\u300110\u5e74\u4ee5\u4e0a\uff08\u6b6f\u304e\u3057\u308a\u304c\u3042\u308b\u5834\u5408\u306f\u30ca\u30a4\u30c8\u30ac\u30fc\u30c9\u304c\u5fc5\u8981\uff09<\/div><\/div><\/div><\/td><\/tr><tr class=\"jet-table__body-row elementor-repeater-item-bf9021b\"><td class=\"jet-table__cell elementor-repeater-item-1ab22d0 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u4fa1\u683c<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-3019512 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u6bd4\u8f03\u7684\u5b89\u3044<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-075a0c5 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u3084\u3084\u9ad8\u3081<br>\n(20000~30000\u5143)<\/div><\/div><\/div><\/td><\/tr><tr class=\"jet-table__body-row elementor-repeater-item-b0df990\"><td class=\"jet-table__cell elementor-repeater-item-45caa9e jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u30e1\u30ea\u30c3\u30c8<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-1d5e7bd jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u5b89\u4fa1<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-8235b9b jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u5916\u89b3\u304c\u81ea\u7136\u3067\u7f8e\u3057\u3044<\/div><\/div><\/div><\/td><\/tr><\/tbody>\n\t\t\t<\/table>\n\t\t<\/div>\n\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e723e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e723e8\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef6ce96\" data-id=\"ef6ce96\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cded7c1 elementor-widget elementor-widget-text-editor\" data-id=\"cded7c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u3010\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306b\u3088\u308b\u30db\u30ef\u30a4\u30c8\u30cb\u30f3\u30b0\u3068\u5f93\u6765\u306e\u30af\u30e9\u30a6\u30f3\u306e\u9055\u3044\u3011\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fdc810f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdc810f\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-66a0c97\" data-id=\"66a0c97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-861a693 elementor-widget elementor-widget-text-editor\" data-id=\"861a693\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u3010\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306f\u30db\u30ef\u30a4\u30c8\u30cb\u30f3\u30b0\u3060\u3051\u3067\u306a\u304f\u3001\u672c\u7269\u306e\u6b6f\u306e\u8272\u306b\u8fd1\u3044\u8272\u8abf\u8abf\u6574\u3082\u53ef\u80fd\u3011<\/strong><\/p><p><strong>\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3067\u306f\u3001\u60a3\u8005\u306e\u808c\u306e\u8272\u3084\u5143\u306e\u6b6f\u306e\u8272\u306b\u5408\u308f\u305b\u305f\u3001\u6700\u3082\u8abf\u548c\u306e\u3068\u308c\u305f\u7fa9\u6b6f\u304c\u4f5c\u308c\u307e\u3059\u3002\u307e\u305f\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u306f\u3001\u4ed6\u306e\u7fa9\u6b6f\u7d20\u6750\u306b\u6bd4\u3079\u3066\u900f\u660e\u5ea6\u304c\u9ad8\u3044\u7d20\u6750\u3067\u3042\u308b\u305f\u3081\u3001\u5143\u306e\u6b6f\u306e\u8272\u306b\u8fd1\u304f\u3001\u81ea\u7136\u5149\u306e\u4e0b\u3067\u3082\u672c\u7269\u3068\u898b\u5206\u3051\u304c\u3064\u304b\u306a\u3044\u307b\u3069\u81ea\u7136\u306a\u8272\u5408\u3044\u3068\u900f\u660e\u611f\u304c\u8868\u73fe\u3067\u304d\u307e\u3059\u3002\u81ea\u7136\u3067\u7f8e\u3057\u3044\u4ed5\u4e0a\u304c\u308a\u3092\u91cd\u8996\u3059\u308b\u65b9\u306b\u3068\u3063\u3066\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306f\u7406\u60f3\u7684\u306a\u9078\u629e\u80a2\u3067\u3059\u3002<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5a3f1b8\" data-id=\"5a3f1b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbf0ba7 elementor-widget elementor-widget-text-editor\" data-id=\"fbf0ba7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u30103D\u30c7\u30b8\u30bf\u30eb\u6b6f\u578b\u5f6b\u523b\u306b\u3088\u308b\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3067\u3001\u6b6f\u306e\u30db\u30ef\u30a4\u30c8\u30cb\u30f3\u30b0\u304c\u4e00\u65e5\u3067\u5b8c\u6210\u3011<\/strong><\/p><p><strong>\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u8907\u96d1\u306a\u88fd\u9020\u5de5\u7a0b\u3067\u306f\u3001\u672c\u7269\u306e\u6b6f\u306b\u8fd1\u3044\u30af\u30e9\u30a6\u30f3\u3092\u88fd\u4f5c\u3059\u308b\u305f\u3081\u306b\u533b\u5e2b\u3068\u6b6f\u79d1\u6280\u5de5\u58eb\u306e\u5c02\u9580\u7684\u306a\u5354\u529b\u304c\u5fc5\u8981\u3068\u306a\u308a\u307e\u3059\u3002\u5f53\u30af\u30ea\u30cb\u30c3\u30af\u3067\u306f\u3001CAD\/CAM\u30c7\u30b8\u30bf\u30eb\u6280\u8853\u306b\u3088\u308a\u3001\u30b3\u30f3\u30d4\u30e5\u30fc\u30bf\u30b7\u30df\u30e5\u30ec\u30fc\u30b7\u30e7\u30f3\u304b\u3089\u7fa9\u6b6f\u306e\u88fd\u4f5c\u3001\u7814\u78e8\u3001\u7740\u8272\u3001\u713c\u4ed8\u307e\u3067\u3092\u30af\u30ea\u30cb\u30c3\u30af\u5185\u3067\u3001\u304b\u3064\u4e00\u65e5\u3067\u5b8c\u4e86\u3055\u305b\u308b\u3053\u3068\u304c\u3067\u304d\u3001\u30e9\u30df\u30cd\u30fc\u30c8\u3079\u30cb\u30a2\u3082\u4e00\u65e5\u3067\u5b8c\u6210\u3057\u307e\u3059\u3002<br \/><\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-514c7c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"514c7c5\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b54af72\" data-id=\"b54af72\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f26f360 elementor-widget elementor-widget-text-editor\" data-id=\"f26f360\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u3010\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u624b\u8853\u306f\u5f8c\u907a\u75c7\u306e\u53ef\u80fd\u6027\u304c\u4f4e\u304f\u3001\u5b89\u5fc3\u3011<\/strong><\/p><p><strong>\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u7d20\u6750\u306f\u4eba\u4f53\u3068\u306e\u751f\u4f53\u89aa\u548c\u6027\u304c\u9ad8\u3044\u305f\u3081\u3001\u30af\u30e9\u30a6\u30f3\u304c\u6b6f\u8089\u3068\u63a5\u89e6\u3059\u308b\u90e8\u5206\u306b\u708e\u75c7\u3084\u30a2\u30ec\u30eb\u30ae\u30fc\u3092\u8d77\u3053\u3057\u306b\u304f\u304f\u3001\u5fb9\u5e95\u7684\u306a\u6e05\u6383\u3092\u884c\u3048\u3070\u3001\u975e\u5e38\u306b\u9577\u6301\u3061\u3057\u307e\u3059\u3002\u91d1\u5c5e\u7d20\u6750\u3067\u8d77\u3053\u308b\u6b6f\u8089\u306e\u7740\u8272\u3001\u6b6f\u8089\u306e\u9732\u51fa\u3001\u91d1\u5c5e\u306e\u71b1\u4f1d\u5c0e\u306b\u3088\u308b\u6b6f\u306e\u77e5\u899a\u904e\u654f\u306a\u3069\u306e\u554f\u984c\u3092\u89e3\u6c7a\u3067\u304d\u308b\u3053\u3068\u304b\u3089\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3092\u9078\u3076\u4eba\u304c\u5897\u3048\u3066\u3044\u307e\u3059\u3002<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-00238dc\" data-id=\"00238dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5670741 elementor-widget elementor-widget-text-editor\" data-id=\"5670741\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u3010\u5916\u89b3\u306e\u6bd4\u8f03\u3011\u5f93\u6765\u306e\u30af\u30e9\u30a6\u30f3\u306e\u4e0d\u81ea\u7136\u306a\u767d\u3055\u3084\u5909\u8272\u3059\u308b\u6b20\u70b9\u3092\u89e3\u6c7a\u3059\u308b\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3<br \/><\/strong><\/p><p><strong>\u5f93\u6765\u306e\u30af\u30e9\u30a6\u30f3\u306f\u3001\u898b\u305f\u76ee\u306f\u30bb\u30e9\u30df\u30c3\u30af\u3067\u3059\u304c\u3001\u5185\u5074\u306b\u91d1\u5c5e\u5185\u51a0\u304c\u3042\u308a\u3001\u305d\u306e\u90e8\u5206\u3068\u6b6f\u306b\u63a5\u89e6\u3057\u3066\u3044\u308b\u7b87\u6240\u3068\u304c\u5341\u5206\u306b\u6e05\u6383\u3055\u308c\u3066\u3044\u306a\u3044\u5834\u5408\u3001\u91d1\u5c5e\u30a4\u30aa\u30f3\u304c\u7d30\u83cc\u3068\u6df7\u3056\u3063\u3066\u6642\u9593\u306e\u7d4c\u904e\u3068\u3068\u3082\u306b\u67d3\u307f\u51fa\u3057\u305f\u7d50\u679c\u3001\u6b6f\u8089\u306e\u5909\u8272\u3092\u5f15\u304d\u8d77\u3053\u3057\u3084\u3059\u304f\u306a\u308a\u3001\u4e00\u822c\u7684\u306b\u898b\u3089\u308c\u308b\u3088\u3046\u306a\u9ed2\u305a\u3093\u3060\u6b6f\u830e\u306b\u306a\u3063\u3066\u3057\u307e\u3044\u307e\u3059\u3002\u307e\u305f\u3001\u91d1\u5c5e\u306e\u5185\u90e8\u306f\u5149\u3092\u901a\u3055\u306a\u3044\u305f\u3081\u3001\u91d1\u5c5e\u5185\u51a0\u306e\u7fa9\u6b6f\u306f\u3001\u4e0d\u81ea\u7136\u306b\u767d\u304f\u898b\u3048\u3066\u3057\u307e\u3046\u306e\u3067\u3059\u3002<br \/><\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-145f5ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"145f5ba\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-be6119d\" data-id=\"be6119d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9749c8 elementor-widget elementor-widget-text-editor\" data-id=\"e9749c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u3010\u5b89\u5168\u6027\u3068\u5bff\u547d\u306e\u6bd4\u8f03\u3011\u91d1\u5c5e\u52a3\u5316\u3001\u91cd\u91d1\u5c5e\u6bd2\u7d20\u306e\u5371\u967a\u6027\u304c\u3042\u308b<\/strong><\/p><p><strong>\u5f93\u6765\u306e\u30af\u30e9\u30a6\u30f3\u306e\u7d20\u6750\u306f\u3001\u4e00\u822c\u7684\u306a\u91d1\u5c5e\u3001\u534a\u8cb4\u91d1\u5c5e\u3001\u9ad8\u8cb4\u91d1\u5c5e\u306b\u5206\u3051\u3089\u308c\u307e\u3059\u3002\u7fa9\u6b6f\u306e\u88fd\u4f5c\u6642\u306b\u306f\u5fc5\u305a\u91d1\u5c5e\u306e\u7d20\u6750\u3092\u78ba\u8a8d\u3059\u308b\u3088\u3046\u306b\u3057\u3066\u304f\u3060\u3055\u3044\u3002\u60a3\u8005\u69d8\u306b\u3088\u3063\u3066\u306f\u3001\u4f7f\u7528\u5f8c\u3001\u91d1\u5c5e\u30a4\u30aa\u30f3\u304c\u904a\u96e2\u3057\u3066\u3057\u307e\u3044\u3001\u6b6f\u8089\u306e\u5468\u308a\u304c\u9ed2\u304f\u306a\u308b\u3053\u3068\u304c\u3042\u308a\u307e\u3059\u3002\u8cea\u306e\u60aa\u3044\u91d1\u5c5e\u7d20\u6750\u3092\u4f7f\u7528\u3057\u305f\u7fa9\u6b6f\u306f\u3001\u30a2\u30ec\u30eb\u30ae\u30fc\u3084\u708e\u75c7\u3092\u8d77\u3053\u3057\u3084\u3059\u304f\u3001\u91cd\u91d1\u5c5e\u6bd2\u7d20\u306e\u5371\u967a\u6027\u3082\u3042\u308a\u307e\u3059\u3002<br \/><\/strong><\/p><p><strong>\u5f93\u6765\u306e\u30af\u30e9\u30a6\u30f3\u304c\u3059\u3067\u306b\u300c\u6b6f\u8089\u5468\u8fba\u306e\u5909\u8272\u300d\u3084\u300c\u9069\u5408\u4e0d\u826f\u300d\u3092\u5f15\u304d\u8d77\u3053\u3057\u3066\u3044\u308b\u5834\u5408\u306b\u3082\u3001\u65b0\u305f\u306b\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3092\u88fd\u4f5c\u3059\u308b\u3053\u3068\u3092\u304a\u52e7\u3081\u3057\u307e\u3059\u3002\u91d1\u5c5e\u6210\u5206\u3092\u542b\u307e\u306a\u3044\u305f\u3081\u5b89\u5fc3\u3057\u3066\u6b6f\u8089\u306e\u5909\u8272\u3084\u9ed2\u305a\u307f\u306e\u554f\u984c\u3092\u52b9\u7387\u7684\u306b\u89e3\u6c7a\u3067\u304d\u3001\u3088\u308a\u65e9\u3044\u30db\u30ef\u30a4\u30c8\u30cb\u30f3\u30b0\u52b9\u679c\u304c\u671f\u5f85\u3067\u304d\u307e\u3059\u3002<br \/><\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-489fddc\" data-id=\"489fddc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a2d2d3 elementor-widget elementor-widget-text-editor\" data-id=\"0a2d2d3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>\u3010\u6839\u7ba1\u6cbb\u7642\u5f8c\u306e\u6700\u9069\u306a\u30d1\u30fc\u30c8\u30ca\u30fc\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306b\u3088\u308b\u4fdd\u8b77\u3011<\/strong><\/p><p><strong>\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u8907\u96d1\u306a\u88fd\u9020\u5de5\u7a0b\u3067\u306f\u3001\u672c\u7269\u306e\u6b6f\u306b\u8fd1\u3044\u30af\u30e9\u30a6\u30f3\u3092\u88fd\u4f5c\u3059\u308b\u305f\u3081\u306b\u533b\u5e2b\u3068\u6b6f\u79d1\u6280\u5de5\u58eb\u306e\u5c02\u9580\u7684\u306a\u5354\u529b\u304c\u5fc5\u8981\u3068\u306a\u308a\u307e\u3059\u3002\u5f53\u30af\u30ea\u30cb\u30c3\u30af\u3067\u306f\u3001CAD\/CAM\u30c7\u30b8\u30bf\u30eb\u6280\u8853\u306b\u3088\u308a\u3001\u30b3\u30f3\u30d4\u30e5\u30fc\u30bf\u30b7\u30df\u30e5\u30ec\u30fc\u30b7\u30e7\u30f3\u304b\u3089\u7fa9\u6b6f\u306e\u88fd\u4f5c\u3001\u7814\u78e8\u3001\u7740\u8272\u3001\u713c\u4ed8\u307e\u3067\u3092\u30af\u30ea\u30cb\u30c3\u30af\u5185\u3067\u3001\u304b\u3064\u4e00\u65e5\u3067\u5b8c\u4e86\u3055\u305b\u308b\u3053\u3068\u304c\u3067\u304d\u3001\u30e9\u30df\u30cd\u30fc\u30c8\u3079\u30cb\u30a2\u3082\u4e00\u65e5\u3067\u5b8c\u6210\u3057\u307e\u3059\u3002<br \/><\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f4725a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f4725a\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22be4f4\" data-id=\"22be4f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e84966 elementor-widget elementor-widget-text-editor\" data-id=\"5e84966\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u3010\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u7d20\u6750\u306e\u7d39\u4ecb\u3011\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-707562d elementor-widget elementor-widget-text-editor\" data-id=\"707562d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u6700\u3082\u4e00\u822c\u7684\u306a\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u7a2e\u985e\u306f\u30cb\u30b1\u30a4\u9178\u30ea\u30c1\u30a6\u30e0\u3001\u30b8\u30eb\u30b3\u30cb\u30a2\u306e\uff12\u7a2e\u985e\u3067\u3059\u3002\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-84336e1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"84336e1\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ffd44f6\" data-id=\"ffd44f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d1ca93 elementor-widget elementor-widget-text-editor\" data-id=\"8d1ca93\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u25aa \u4e8c\u6c27\u5316\u92ef\u30b8\u30eb\u30b3\u30cb\u30a2\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0886fbd elementor-widget elementor-widget-text-editor\" data-id=\"0886fbd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u751f\u4f53\u89aa\u548c\u6027\u304c\u9ad8\u304f\u3001\u901a\u5e38\u306e\u6b6f\u306e2\uff5e3\u500d\u306e\u786c\u3055\u304c\u3042\u308b\u306e\u3067\u3001\u5f8c\u6b6f\u306b\u9069\u3057\u3066\u3044\u307e\u3059\u6700\u8fd1\u306e\u30b8\u30eb\u30b3\u30cb\u30a2\u306e\u7d20\u6750\u306f\u3001\u975e\u5e38\u306b\u7f8e\u3057\u304f\u4f5c\u308c\u308b\u305f\u3081\u3001\u524d\u6b6f\u306b\u3082\u4f7f\u7528\u3067\u304d\u307e\u3059\u3002\u6b6f\u304e\u3057\u308a\u3084\u786c\u3044\u3082\u306e\u3092\u565b\u3080\u7fd2\u6163\u304c\u3042\u308a\u3001\u5be9\u7f8e\u6027\u306b\u3082\u6c17\u3092\u914d\u308a\u305f\u3044\u60a3\u8005\u3055\u3093\u306b\u3068\u3063\u3066\u3001\u30b8\u30eb\u30b3\u30cb\u30a2\u306f\u6700\u9069\u306a\u7d20\u6750\u3067\u3059\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbc5e4f elementor-widget elementor-widget-text-editor\" data-id=\"cbc5e4f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u25aa \u30cb\u30b1\u30a4\u9178\u30ea\u30c1\u30a6\u30e0\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec3ccc3 elementor-widget elementor-widget-text-editor\" data-id=\"ec3ccc3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u3044\u308f\u3086\u308b\u30ac\u30e9\u30b9\u30bb\u30e9\u30df\u30c3\u30af\u30b9\u306e\u3053\u3068\u3067\u3001\u672c\u7269\u306e\u6b6f\u306b\u8fd1\u3044\u8272\u5408\u3044\u3092\u6301\u3061\u3001\u5149\u306e\u900f\u904e\u6027\u306b\u512a\u308c\u3066\u3044\u307e\u3059\u304c\u3001\u30b8\u30eb\u30b3\u30cb\u30a2\u3068\u6bd4\u8f03\u3059\u308b\u3068\u786c\u5ea6\u306e\u9762\u3067\u3084\u3084\u52a3\u308b\u305f\u3081\u3001\u524d\u6b6f\u3084\u9580\u6b6f\u306b\u306e\u307f\u9069\u3057\u3066\u3044\u307e\u3059\u3002\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c52249a\" data-id=\"c52249a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7098c57 elementor-widget elementor-widget-jet-table\" data-id=\"7098c57\" data-element_type=\"widget\" data-widget_type=\"jet-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-table jet-elements\">\n\t\t<div class=\"jet-table-wrapper jet-table-responsive-mobile\">\n\t\t\t<table class=\"jet-table jet-table--fa5-compat\">\n\t\t\t\t<thead class=\"jet-table__head\"><tr class=\"jet-table__head-row\"><th class=\"jet-table__cell elementor-repeater-item-7c5a22a jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-65d731f jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u30b8\u30eb\u30b3\u30cb\u30a2<\/div><\/div><\/div><\/th><th class=\"jet-table__cell elementor-repeater-item-18a3ee0 jet-table__head-cell\" scope=\"col\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u30cb\u30b1\u30a4\u9178\u30ea\u30c1\u30a6\u30e0<\/div><\/div><\/div><\/th><\/tr><\/thead>\n\t\t\t\t\t\t\t\t<tbody class=\"jet-table__body\"><tr class=\"jet-table__body-row elementor-repeater-item-e0452f3\"><td class=\"jet-table__cell elementor-repeater-item-200fbbb jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u4e00\u822c\u7684\u306a\u30d6\u30e9\u30f3\u30c9<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-ad3f62d jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">Cercon\u30013M Lava\u3001TDS\u3001Wieland\u3001Vita\u7b49<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-14e0553 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">E-max\u3001Celtra Duo<\/div><\/div><\/div><\/td><\/tr><tr class=\"jet-table__body-row elementor-repeater-item-4b3881d\"><td class=\"jet-table__cell elementor-repeater-item-a2f1d2c jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u786c\u3055<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-34bde1b jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u901a\u5e38\u306e\u6b6f\u306e2\uff5e3\u500d<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-0dac353 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u666e\u901a<\/div><\/div><\/div><\/td><\/tr><tr class=\"jet-table__body-row elementor-repeater-item-c7cbf94\"><td class=\"jet-table__cell elementor-repeater-item-fd9a9e7 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u9069\u7528\u90e8\u4f4d<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-431190f jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u5f8c\u6b6f\u3001\u524d\u6b6f<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-209ddd3 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u524d\u6b6f<\/div><\/div><\/div><\/td><\/tr><tr class=\"jet-table__body-row elementor-repeater-item-bf9021b\"><td class=\"jet-table__cell elementor-repeater-item-1ab22d0 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u4fa1\u683c<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-3019512 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u30af\u30ea\u30cb\u30c3\u30af\u306b\u3088\u308b<\/div><\/div><\/div><\/td><td class=\"jet-table__cell elementor-repeater-item-075a0c5 jet-table__body-cell\"><div class=\"jet-table__cell-inner\"><div class=\"jet-table__cell-content\"><div class=\"jet-table__cell-text\">\u30af\u30ea\u30cb\u30c3\u30af\u306b\u3088\u308b<\/div><\/div><\/div><\/td><\/tr><\/tbody>\n\t\t\t<\/table>\n\t\t<\/div>\n\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8729c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8729c4\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-810a333\" data-id=\"810a333\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70491e9 elementor-widget elementor-widget-text-editor\" data-id=\"70491e9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u3010\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u9069\u5fdc\u75c7\u3011\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c62d9c6 elementor-widget elementor-widget-text-editor\" data-id=\"c62d9c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306f\u3001\u4ee5\u4e0b\u306e\u3088\u3046\u306a\u75c7\u4f8b\u306b\u9069\u3057\u3066\u3044\u307e\u3059\u3002\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6155f1a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6155f1a\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8647384\" data-id=\"8647384\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3e6879 elementor-widget elementor-widget-text-editor\" data-id=\"a3e6879\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e81e77e elementor-widget elementor-widget-text-editor\" data-id=\"e81e77e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u91cd\u5ea6\u306e\u866b\u6b6f\u304c\u3042\u308b\u5834\u5408\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c7e7fd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8c7e7fd\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb7ccda elementor-widget elementor-widget-text-editor\" data-id=\"eb7ccda\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u866b\u6b6f\u306e\u9032\u884c\u306b\u3088\u3063\u3066\u6b6f\u304c\u654f\u611f\u306b\u306a\u308a\u3001\u4e14\u3064\u6b6f\u306e\u6b20\u640d\u304c\u5927\u304d\u3044\u5834\u5408\u3001\u5358\u306b\u5145\u586b\u3059\u308b\u3060\u3051\u3067\u306f\u6b6f\u3092\u5b89\u5b9a\u3055\u305b\u308b\u3053\u3068\u306f\u3067\u304d\u307e\u305b\u3093\u304c\u3001\u6839\u7ba1\u6cbb\u7642\u306e\u6bb5\u968e\u307e\u3067\u9032\u884c\u3057\u3066\u3044\u306a\u3044\u30b1\u30fc\u30b9\u3067\u306f\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3067\u6b6f\u306e\u3055\u3089\u306a\u308b\u640d\u50b7\u3084\u4e80\u88c2\u7bc4\u56f2\u306e\u62e1\u5927\u3092\u9632\u3050\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7cb65c3\" data-id=\"7cb65c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4baff0 elementor-widget elementor-widget-text-editor\" data-id=\"f4baff0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>2<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c56b3e9 elementor-widget elementor-widget-text-editor\" data-id=\"c56b3e9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u6839\u7ba1\u6cbb\u7642\u3092\u53d7\u3051\u305f\u3053\u3068\u304c\u3042\u308b\u5834\u5408\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c5afcb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6c5afcb\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4322ddd elementor-widget elementor-widget-text-editor\" data-id=\"4322ddd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u300c\u6839\u7ba1\u6cbb\u7642\u300d\u3068\u306f\u3064\u307e\u308a\u300c\u795e\u7d4c\u3092\u629c\u304f\u300d\u3068\u3044\u3046\u3053\u3068\u3067\u3059\u304c\u3001\u795e\u7d4c\u3092\u629c\u3044\u305f\u5f8c\u306e\u6b6f\u306f\u5f31\u304f\u306a\u308b\u305f\u3081\u3001\u786c\u3044\u3082\u306e\u3092\u565b\u3093\u3060\u308a\u3059\u308b\u3053\u3068\u306b\u3088\u308b\u30c0\u30e1\u30fc\u30b8\u3084\u6b6f\u6839\u7834\u6298\u304b\u3089\u672c\u7269\u306e\u6b6f\u3092\u5b88\u308b\u305f\u3081\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3067\u6b6f\u3092\u5b89\u5b9a\u3055\u305b\u308b\u3053\u3068\u3092\u304a\u52e7\u3081\u3057\u307e\u3059\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ae87c28\" data-id=\"ae87c28\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-635c4cc elementor-widget elementor-widget-text-editor\" data-id=\"635c4cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>3<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01142b9 elementor-widget elementor-widget-text-editor\" data-id=\"01142b9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u4e8b\u6545\u306b\u3088\u308b\u6b6f\u306e\u7834\u6298\u304c\u3042\u308b\u5834\u5408\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad21739 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ad21739\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bab8b2 elementor-widget elementor-widget-text-editor\" data-id=\"3bab8b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u6b6f\u306f\u786c\u3044\u7d44\u7e54\u3067\u3042\u308b\u305f\u3081\u3001\u81ea\u7136\u6cbb\u7652\u3059\u308b\u3053\u3068\u306f\u3067\u304d\u307e\u305b\u3093\u3002\u6b6f\u306e\u7834\u640d\u304c1\/3\u3092\u8d85\u3048\u3066\u3044\u306a\u3044\u5834\u5408\u306f\u30013D\u6b6f\u578b\u5f6b\u523b\u3067\u88dc\u4fee\u3067\u304d\u308b\u5834\u5408\u3082\u3042\u308a\u307e\u3059\u304c\u3001\u7834\u6298\u304c\u5927\u304d\u3059\u304e\u308b\u5834\u5408\u306b\u306f\u3001\u6839\u7ba1\u6cbb\u7642\u3092\u884c\u3063\u305f\u5f8c\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3067\u54ac\u5408\u529b\u3092\u56de\u5fa9\u3055\u305b\u308b\u3053\u3068\u3092\u304a\u52e7\u3081\u3057\u307e\u3059\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9c6bb89\" data-id=\"9c6bb89\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b16f4d elementor-widget elementor-widget-text-editor\" data-id=\"1b16f4d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>4<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-123b432 elementor-widget elementor-widget-text-editor\" data-id=\"123b432\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u6b6f\u306e\u6b20\u640d\u304c\u3042\u308a\u3001\u30d6\u30ea\u30c3\u30b8\u3092\u5fc5\u8981\u3068\u3059\u308b\u5834\u5408\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7237a4f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7237a4f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a307c98 elementor-widget elementor-widget-text-editor\" data-id=\"a307c98\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u6b6f\u306e\u6b20\u640d\u3092\u653e\u7f6e\u3059\u308b\u3068\u3001\u4ed6\u306e\u6b6f\u304c\u7de9\u3093\u3067\u79fb\u52d5\u3059\u308b\u53ef\u80fd\u6027\u304c\u3042\u308a\u307e\u3059\u3002\u30a4\u30f3\u30d7\u30e9\u30f3\u30c8\u3092\u9078\u629e\u3057\u306a\u3044\u5834\u5408\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306b\u3088\u308b\u30d6\u30ea\u30c3\u30b8\u306f\u6b6f\u306e\u6b20\u640d\u3092\u5145\u586b\u3059\u308b\u3082\u3046\u4e00\u3064\u306e\u65b9\u6cd5\u3067\u3059\u3002\u3064\u307e\u308a\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3092\u4f7f\u7528\u3057\u3066\u6b6f\u3092\u518d\u5efa\u3057\u3001\u53e3\u8154\u5185\u306e\u5931\u3063\u305f\u6b6f\u3092\u88dc\u586b\u3059\u308b\u3068\u3044\u3046\u3053\u3068\u3067\u3059\u3002\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a0f958 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2a0f958\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8182c38\" data-id=\"8182c38\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-214f191 elementor-widget elementor-widget-text-editor\" data-id=\"214f191\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>5<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e72e068 elementor-widget elementor-widget-text-editor\" data-id=\"e72e068\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u65e2\u5b58\u306e\u7fa9\u6b6f\u306e\u7de9\u307f\u3084\u30d6\u30ea\u30c3\u30b8\u304c\u5bc6\u7740\u3057\u3066\u3044\u306a\u3044\u5834\u5408\f\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3220e0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c3220e0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c05c97 elementor-widget elementor-widget-text-editor\" data-id=\"9c05c97\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u6b6f\u306e\u565b\u3080\u529b\u306f\u3001\u6b6f\u81ea\u4f53\u306e\u5b89\u5b9a\u6027\u306b\u95a2\u4fc2\u3057\u3066\u304a\u308a\u3001\u7fa9\u6b6f\u304c\u7de9\u3093\u3067\u3044\u308b\u3001\u307e\u305f\u306f\u30d6\u30ea\u30c3\u30b8\u304c\u5b89\u5b9a\u3057\u3066\u3044\u306a\u3044\u5834\u5408\u3001\u4e8c\u6b21\u7684\u306a\u866b\u6b6f\u306e\u539f\u56e0\u3068\u306a\u308a\u307e\u3059\u3002\u305d\u306e\u5834\u5408\u306f\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3067\u65b0\u305f\u306b\u3088\u308a\u81ea\u7136\u3067\u7f8e\u3057\u3044\u7fa9\u6b6f\u3092\u4f5c\u308b\u3053\u3068\u3092\u304a\u52e7\u3081\u3057\u307e\u3059\u3002\u4f55\u65e5\u3082\u5f85\u3064\u3053\u3068\u306a\u304f\u3001\u305d\u306e\u65e5\u306e\u3046\u3061\u306b\u3059\u3050\u88c5\u7740\u3059\u308b\u3053\u3068\u304c\u3067\u304d\u307e\u3059\u3002\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ce0fc32\" data-id=\"ce0fc32\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fa27a1 elementor-widget elementor-widget-text-editor\" data-id=\"5fa27a1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>6<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87d8f22 elementor-widget elementor-widget-text-editor\" data-id=\"87d8f22\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u65e2\u5b58\u306e\u30b3\u30f3\u30dd\u30b8\u30c3\u30c8\u30ec\u30b8\u30f3\uff08\u5145\u586b\u5264\uff09\u304c\u5909\u8272\u3057\u305f\u308a\u3001\u5bc6\u7740\u3057\u3066\u3044\u306a\u3044\u5834\u5408\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd456a0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dd456a0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cb5422 elementor-widget elementor-widget-text-editor\" data-id=\"4cb5422\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u98df\u7fd2\u6163\u306b\u3088\u3063\u3066\u8d77\u3053\u308b\u6a39\u8102\u7d20\u6750\u306e\u5909\u8272\u306f\u3001\u6b6f\u306e\u5be9\u7f8e\u6027\u3092\u5927\u304d\u304f\u4f4e\u4e0b\u3055\u305b\u307e\u3059\u3002\u3053\u306e\u72b6\u6cc1\u3092\u6539\u5584\u3057\u305f\u308a\u3001\u4e8c\u6b21\u7684\u306a\u866b\u6b6f\u3092\u9632\u304e\u305f\u3044\u5834\u5408\u3001CAD-CAM-3D\u6b6f\u578b\u5f6b\u523b\u3092\u4f7f\u7528\u3059\u308b\u3068\u3001\u305d\u306e\u5834\u3067\u6700\u9069\u306a\u6b6f\u306e\u8272\u306b\u7814\u78e8\u3001\u713c\u4ed8\u304c\u3067\u304d\u3001\u5bc6\u7740\u5ea6\u306e\u9762\u3067\u3082\u975e\u5e38\u306b\u512a\u308c\u305f\u52b9\u679c\u3092\u767a\u63ee\u3057\u307e\u3059\u3002\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dad3429\" data-id=\"dad3429\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0408992 elementor-widget elementor-widget-text-editor\" data-id=\"0408992\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>7<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bd5e0a elementor-widget elementor-widget-text-editor\" data-id=\"8bd5e0a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u9280\u7c89\u5145\u586b\u5264\u3092\u4f7f\u7528\u3057\u3066\u3044\u308b\u5834\u5408\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86c1d41 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"86c1d41\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2617725 elementor-widget elementor-widget-text-editor\" data-id=\"2617725\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u8fd1\u5e74\u3001\u4eba\u3005\u306e\u9593\u3067\u9280\u7c89\u306e\u4f7f\u7528\u306b\u5bfe\u3059\u308b\u61f8\u5ff5\u304c\u9ad8\u307e\u3063\u3066\u304a\u308a\u3001\u9178\u5316\u3057\u3066\u9ed2\u305a\u307f\u3084\u3059\u3044\u306a\u3069\u306e\u554f\u984c\u3082\u3042\u308b\u305f\u3081\u3001\u5f90\u3005\u306b\u30bb\u30e9\u30df\u30c3\u30af\u306a\u3069\u306e\u6750\u6599\u306b\u3068\u3063\u3066\u4ee3\u308f\u3089\u308c\u3066\u3044\u307e\u3059\u3002\u60a3\u8005\u69d8\u304c\u9280\u7c89\u5145\u586b\u306e\u6b6f\uff08\u9280\u6b6f\uff09\u306e\u7f8e\u89b3\u8abf\u6574\u3092\u5e0c\u671b\u3059\u308b\u5834\u5408\u306b\u306f\u3001CAD-CAM 3D\u6b6f\u578b\u5f6b\u523b\u3092\u65b0\u305f\u306a\u9078\u629e\u80a2\u3068\u3057\u3066\u3082\u3088\u3044\u3067\u3057\u3087\u3046\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e724cc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0e724cc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2351e6\" data-id=\"b2351e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e6a356 elementor-widget elementor-widget-text-editor\" data-id=\"0e6a356\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u3010\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3Q&#038;A\u3011\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99ab784 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"99ab784\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;2&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a0bdc64 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a0bdc64\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b7e274\" data-id=\"1b7e274\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-257a2e3 elementor-widget elementor-widget-text-editor\" data-id=\"257a2e3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tQ.\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u5bff\u547d\u306f\u3069\u306e\u304f\u3089\u3044\u3067\u3059\u304b\uff1f\u4e00\u751f\u4f7f\u3048\u307e\u3059\u304b\uff1f\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7ee967 elementor-widget elementor-widget-text-editor\" data-id=\"f7ee967\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u6b63\u3057\u3044\u6e05\u6383\u65b9\u6cd5\u3068\u826f\u597d\u306a\u53e3\u8154\u6e05\u6f54\u7fd2\u6163\u306e\u4e0b\u3067\u306f\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306f\u9577\u671f\u9593\u4f7f\u7528\u3067\u304d\u307e\u3059\uff08\u591a\u304f\u306e\u5834\u5408\u300110\u5e74\u4ee5\u4e0a\uff09\u3002\u30af\u30ea\u30cb\u30c3\u30af\u3067\u88fd\u4f5c\u3055\u308c\u305f\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306b\u306f\u4fdd\u8a3c\u3082\u3064\u3044\u3066\u3044\u308b\u305f\u3081\u3001\u3088\u3044\u53e3\u8154\u30b1\u30a2\u306e\u7fd2\u6163\u3092\u7dad\u6301\u3057\u3066\u3044\u308c\u3070\u3001\u904e\u5ea6\u306b\u5fc3\u914d\u3059\u308b\u5fc5\u8981\u306f\u3042\u308a\u307e\u305b\u3093\u3002\u534a\u5e74\u3054\u3068\u306b\u53e3\u8154\u691c\u67fb\u3067\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u72b6\u6cc1\u3092\u78ba\u8a8d\u3059\u308b\u3053\u3068\u3082\u304a\u52e7\u3081\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-743d134 elementor-widget elementor-widget-text-editor\" data-id=\"743d134\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tQ.\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u7d20\u6750\u306f\u4f55\u3067\u3059\u304b\uff1f\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2beaab5 elementor-widget elementor-widget-text-editor\" data-id=\"2beaab5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306b\u306f\u591a\u304f\u306e\u7a2e\u985e\u304c\u3042\u308a\u3001\u4fa1\u683c\u3082\u7570\u306a\u308a\u307e\u3059\u3002\u4e3b\u306b\u3001\u30ac\u30e9\u30b9\u30bb\u30e9\u30df\u30c3\u30af\u30b9\uff08\u30cb\u30b1\u30a4\u9178\u30ea\u30c1\u30a6\u30e0\uff09\u3068\u30b8\u30eb\u30b3\u30cb\u30a2\u304c\u3042\u308a\u3001\u5f93\u6765\u306e\u91d1\u5c5e\uff0b\u30bb\u30e9\u30df\u30c3\u30af\u306e\u6b6f\u3068\u6bd4\u3079\u3001\u6b6f\u8089\u306e\u5468\u308a\u306b\u5bc6\u7740\u3057\u3066\u3001\u8272\u304c\u81ea\u7136\u3067\u3001\u672c\u7269\u306b\u8fd1\u304f\u3001\u9ad8\u5f37\u5ea6\u3068\u3044\u3046\u5229\u70b9\u304c\u3042\u308a\u307e\u3059\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6149507 elementor-widget elementor-widget-text-editor\" data-id=\"6149507\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tQ.\u55a8\u7c92\u6676\u6b6f\u79d1\u30af\u30ea\u30cb\u30c3\u30af\u3067\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u6cbb\u7642\u3092\u3059\u308b\u5229\u70b9\u306f\u4f55\u3067\u3059\u304b\uff1f\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e96bc54 elementor-widget elementor-widget-text-editor\" data-id=\"e96bc54\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u5f53\u30af\u30ea\u30cb\u30c3\u30af\u3067\u306fCAD\uff0fCAM\u306e\u6280\u8853\u3092\u4f7f\u7528\u3057\u3066\u3044\u308b\u305f\u3081\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u7fa9\u6b6f\u306e\u88fd\u4f5c\u6642\u9593\u3092\u5927\u5e45\u306b\u77ed\u7e2e\u3067\u304d\u307e\u3059\u30023D\u53e3\u8154\u5185\u5199\u771f\u3001CAD\u8a2d\u8a08\u3001CAM\u88fd\u4f5c\u3092\u7d44\u307f\u5408\u308f\u305b\u3066\u6700\u3082\u6b63\u78ba\u3067\u81ea\u7136\u306a\u7fa9\u6b6f\u3092\u88fd\u4f5c\u3057\u307e\u3059\u3002\uff08\u95a2\u9023\u8a18\u4e8b\uff1aCAD-CAM\u30c7\u30b8\u30bf\u30eb\u6b6f\u578b\u5f6b\u523b\uff09\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-364bf17 elementor-widget elementor-widget-text-editor\" data-id=\"364bf17\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tQ.\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u4fa1\u683c\u306f\u3044\u304f\u3089\u3067\u3059\u304b\uff1f\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-632f377 elementor-widget elementor-widget-text-editor\" data-id=\"632f377\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306f\u5065\u5eb7\u4fdd\u967a\u304c\u9069\u7528\u3055\u308c\u306a\u3044\u305f\u3081\u3001\u81ea\u8cbb\u6cbb\u7642\u3068\u306a\u308a\u307e\u3059\u3002\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u4fa1\u683c\u306f\u7d0420,000\uff5e30,000\u5143\u7a0b\u5ea6\u3067\u3059\u3002<\/p><p>\u305d\u3057\u3066\u3001\u305d\u306e\u4ed6\u306e\u53e3\u8154\u624b\u8853\u306b\u306f\u5065\u5eb7\u4fdd\u967a\u304c\u9069\u7528\u3055\u308c\u308b\u305f\u3081\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u4fa1\u683c\u306f\u4eba\u306b\u3088\u3063\u3066\u7570\u306a\u308a\u307e\u3059\u3002\u5f53\u30af\u30ea\u30cb\u30c3\u30af\u3067\u306f\u533b\u5e2b\u3068\u3054\u76f8\u8ac7\u5f8c\u3001\u60a3\u8005\u69d8\u5c02\u7528\u306e\u6cbb\u7642\u30d7\u30e9\u30f3\u306e\u4f5c\u6210\u3068\u4fa1\u683c\u306e\u8a55\u4fa1\u3092\u884c\u3063\u3066\u3044\u307e\u3059\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e22aed6 elementor-widget elementor-widget-text-editor\" data-id=\"e22aed6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tQ.\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306e\u4fa1\u683c\u306b\u9055\u3044\u306f\u3042\u308a\u307e\u3059\u304b\uff1f\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-162f412 elementor-widget elementor-widget-text-editor\" data-id=\"162f412\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u5404\u30af\u30ea\u30cb\u30c3\u30af\u3067\u4f7f\u7528\u3059\u308b\u6280\u8853\u3084\u6750\u6599\u3001\u30bb\u30e9\u30df\u30c3\u30af\u306e\u30d6\u30e9\u30f3\u30c9\u3001\u8a2d\u5099\u306a\u3069\u306e\u8981\u56e0\u306b\u3088\u308a\u3001\u540c\u3058\u6cbb\u7642\u3067\u3082\u4fa1\u683c\u304c\u7570\u306a\u308b\u5834\u5408\u304c\u3042\u308a\u307e\u3059\u3002\u5f53\u30af\u30ea\u30cb\u30c3\u30af\u306b\u76f4\u63a5\u3054\u6765\u9662\u3044\u305f\u3060\u3051\u308c\u3070\u3001\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u6cbb\u7642\u306b\u3064\u3044\u3066\u306e\u8a73\u7d30\u306a\u8aac\u660e\u3084\u60a3\u8005\u69d8\u306b\u5408\u3063\u305f\u6cbb\u7642\u306e\u8cbb\u7528\u306e\u3054\u7d39\u4ecb\u3092\u3055\u305b\u3066\u3044\u305f\u3060\u3051\u307e\u3059\u3002\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-112235c elementor-widget elementor-widget-text-editor\" data-id=\"112235c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tQ.\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306f\u7fa9\u6b6f\u3067\u3059\u304b\uff1f\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-324fd06 elementor-widget elementor-widget-text-editor\" data-id=\"324fd06\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u306f\u3044\u3002\u78ba\u304b\u306b\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u306f\u5f93\u6765\u306e\u91d1\u5c5e\u88fd\u30af\u30e9\u30a6\u30f3\u306a\u3069\u3068\u540c\u69d8\u306b\u7fa9\u6b6f\u306e\u7bc4\u7587\u306b\u5c5e\u3057\u307e\u3059\u304c\u3001\u9ad8\u9f62\u8005\u304c\u4f7f\u7528\u3059\u308b\u53ef\u52d5\u5f0f\u306e\u5165\u308c\u6b6f\u306e\u3088\u3046\u306a\u3082\u306e\u3067\u306f\u306a\u304f\u3001\u53e3\u8154\u30b1\u30a2\u306b\u6ce8\u610f\u3059\u308c\u3070\u666e\u901a\u306b\u4f7f\u7528\u3067\u304d\u308b\u3082\u306e\u3067\u3001\u751f\u6d3b\u306b\u4e0d\u4fbf\u3092\u304d\u305f\u3057\u307e\u305b\u3093\u3002<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Home All-ceramic crown \u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3 \u6839\u7ba1\u6cbb\u7642\u5f8c\u306e\u6b6f\u306e\u6b6f\u830e\u5468\u8fba\u306e\u9ed2\u305a\u307f\u306b\u60a9\u3093\u3067\u3044\u307e\u305b\u3093\u304b\uff1f\u3042\u308b\u3044\u306f\u3001\u6b6f\u306e\u89d2\u304c\u6b20\u3051\u3066\u3057\u307e\u3063\u3066\u60a9\u3093\u3067\u3044\u307e\u305b\u3093\u304b\uff1f\u8fd1\u5e74\u3001\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3\u3092\u4f7f\u7528\u3057\u305f\u6b6f\u306e\u4fee\u5fa9\u304c\u5e74 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_wp_rev_ctl_limit":""},"class_list":["post-8867","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012023\u6750\u8cea\uff06\u58fd\u547d<\/title>\n<meta name=\"description\" content=\"\u4f60\u77e5\u9053\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\u55ce\uff1f\u9084\u5728\u64d4\u5fc3\u5168\u74f7\u51a0\u7259\u5957\u7684\u50f9\u683c\u5f88\u8cb4\u55ce\uff1f\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u544a\u8a34\u4f60\u50b3\u7d71\u548c\u5168\u74f7\u51a0\u7259\u5957\u5047\u7259\u6709\u4ec0\u9ebc\u4e0d\u540c\uff0c\u4ee5\u53ca\u5168\u74f7\u51a0\u7259\u5957\u50f9\u683c\uff0820,000-30,000\u591a\u5143\uff09\u548c\u6750\u8cea\u7684\u5dee\u7570\u4ecb\u7d39\uff0c\u7d66\u60a8\u6700\u5c08\u696d\u7684\u5168\u74f7\u51a0\u7f8e\u767d\u670d\u52d9\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012023\u6750\u8cea\uff06\u58fd\u547d\" \/>\n<meta property=\"og:description\" content=\"\u4f60\u77e5\u9053\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\u55ce\uff1f\u9084\u5728\u64d4\u5fc3\u5168\u74f7\u51a0\u7259\u5957\u7684\u50f9\u683c\u5f88\u8cb4\u55ce\uff1f\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u544a\u8a34\u4f60\u50b3\u7d71\u548c\u5168\u74f7\u51a0\u7259\u5957\u5047\u7259\u6709\u4ec0\u9ebc\u4e0d\u540c\uff0c\u4ee5\u53ca\u5168\u74f7\u51a0\u7259\u5957\u50f9\u683c\uff0820,000-30,000\u591a\u5143\uff09\u548c\u6750\u8cea\u7684\u5dee\u7570\u4ecb\u7d39\uff0c\u7d66\u60a8\u6700\u5c08\u696d\u7684\u5168\u74f7\u51a0\u7f8e\u767d\u670d\u52d9\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/\" \/>\n<meta property=\"og:site_name\" content=\"\u55a8\u7c92\u6676\u7259\u91ab\u8a3a\u6240\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-13T09:09:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Mask-Group-35.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"547\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012023\u6750\u8cea\uff06\u58fd\u547d\" \/>\n<meta name=\"twitter:description\" content=\"\u4f60\u77e5\u9053\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\u55ce\uff1f\u9084\u5728\u64d4\u5fc3\u5168\u74f7\u51a0\u7259\u5957\u7684\u50f9\u683c\u5f88\u8cb4\u55ce\uff1f\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u544a\u8a34\u4f60\u50b3\u7d71\u548c\u5168\u74f7\u51a0\u7259\u5957\u5047\u7259\u6709\u4ec0\u9ebc\u4e0d\u540c\uff0c\u4ee5\u53ca\u5168\u74f7\u51a0\u7259\u5957\u50f9\u683c\uff0820,000-30,000\u591a\u5143\uff09\u548c\u6750\u8cea\u7684\u5dee\u7570\u4ecb\u7d39\uff0c\u7d66\u60a8\u6700\u5c08\u696d\u7684\u5168\u74f7\u51a0\u7f8e\u767d\u670d\u52d9\u3002\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Mask-Group-35.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u5206\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012023\u6750\u8cea\uff06\u58fd\u547d","description":"\u4f60\u77e5\u9053\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\u55ce\uff1f\u9084\u5728\u64d4\u5fc3\u5168\u74f7\u51a0\u7259\u5957\u7684\u50f9\u683c\u5f88\u8cb4\u55ce\uff1f\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u544a\u8a34\u4f60\u50b3\u7d71\u548c\u5168\u74f7\u51a0\u7259\u5957\u5047\u7259\u6709\u4ec0\u9ebc\u4e0d\u540c\uff0c\u4ee5\u53ca\u5168\u74f7\u51a0\u7259\u5957\u50f9\u683c\uff0820,000-30,000\u591a\u5143\uff09\u548c\u6750\u8cea\u7684\u5dee\u7570\u4ecb\u7d39\uff0c\u7d66\u60a8\u6700\u5c08\u696d\u7684\u5168\u74f7\u51a0\u7f8e\u767d\u670d\u52d9\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/","og_locale":"ja_JP","og_type":"article","og_title":"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012023\u6750\u8cea\uff06\u58fd\u547d","og_description":"\u4f60\u77e5\u9053\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\u55ce\uff1f\u9084\u5728\u64d4\u5fc3\u5168\u74f7\u51a0\u7259\u5957\u7684\u50f9\u683c\u5f88\u8cb4\u55ce\uff1f\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u544a\u8a34\u4f60\u50b3\u7d71\u548c\u5168\u74f7\u51a0\u7259\u5957\u5047\u7259\u6709\u4ec0\u9ebc\u4e0d\u540c\uff0c\u4ee5\u53ca\u5168\u74f7\u51a0\u7259\u5957\u50f9\u683c\uff0820,000-30,000\u591a\u5143\uff09\u548c\u6750\u8cea\u7684\u5dee\u7570\u4ecb\u7d39\uff0c\u7d66\u60a8\u6700\u5c08\u696d\u7684\u5168\u74f7\u51a0\u7f8e\u767d\u670d\u52d9\u3002","og_url":"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/","og_site_name":"\u55a8\u7c92\u6676\u7259\u91ab\u8a3a\u6240","article_modified_time":"2023-11-13T09:09:00+00:00","og_image":[{"width":547,"height":400,"url":"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Mask-Group-35.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012023\u6750\u8cea\uff06\u58fd\u547d","twitter_description":"\u4f60\u77e5\u9053\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\u55ce\uff1f\u9084\u5728\u64d4\u5fc3\u5168\u74f7\u51a0\u7259\u5957\u7684\u50f9\u683c\u5f88\u8cb4\u55ce\uff1f\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u544a\u8a34\u4f60\u50b3\u7d71\u548c\u5168\u74f7\u51a0\u7259\u5957\u5047\u7259\u6709\u4ec0\u9ebc\u4e0d\u540c\uff0c\u4ee5\u53ca\u5168\u74f7\u51a0\u7259\u5957\u50f9\u683c\uff0820,000-30,000\u591a\u5143\uff09\u548c\u6750\u8cea\u7684\u5dee\u7570\u4ecb\u7d39\uff0c\u7d66\u60a8\u6700\u5c08\u696d\u7684\u5168\u74f7\u51a0\u7f8e\u767d\u670d\u52d9\u3002","twitter_image":"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2022\/02\/Mask-Group-35.jpg","twitter_misc":{"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"4\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/","url":"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/","name":"\u53f0\u4e2d\u5168\u74f7\u51a0\u50f9\u683c\uff5c\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\uff1f\u592f\uff012023\u6750\u8cea\uff06\u58fd\u547d","isPartOf":{"@id":"https:\/\/www.shining-dc.com.tw\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/#primaryimage"},"image":{"@id":"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/#primaryimage"},"thumbnailUrl":"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2023\/11\/ao3oa-fgks8.webp","datePublished":"2022-02-26T13:53:03+00:00","dateModified":"2023-11-13T09:09:00+00:00","description":"\u4f60\u77e5\u9053\u5168\u74f7\u51a0\u7259\u5957\u662f\u4ec0\u9ebc\u55ce\uff1f\u9084\u5728\u64d4\u5fc3\u5168\u74f7\u51a0\u7259\u5957\u7684\u50f9\u683c\u5f88\u8cb4\u55ce\uff1f\u53f0\u4e2d\u55a8\u7c92\u6676\u7259\u91ab\u544a\u8a34\u4f60\u50b3\u7d71\u548c\u5168\u74f7\u51a0\u7259\u5957\u5047\u7259\u6709\u4ec0\u9ebc\u4e0d\u540c\uff0c\u4ee5\u53ca\u5168\u74f7\u51a0\u7259\u5957\u50f9\u683c\uff0820,000-30,000\u591a\u5143\uff09\u548c\u6750\u8cea\u7684\u5dee\u7570\u4ecb\u7d39\uff0c\u7d66\u60a8\u6700\u5c08\u696d\u7684\u5168\u74f7\u51a0\u7f8e\u767d\u670d\u52d9\u3002","breadcrumb":{"@id":"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/#primaryimage","url":"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2023\/11\/ao3oa-fgks8.webp","contentUrl":"https:\/\/www.shining-dc.com.tw\/wp-content\/uploads\/2023\/11\/ao3oa-fgks8.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.shining-dc.com.tw\/ja\/all-ceramic-crown\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/www.shining-dc.com.tw\/ja\/"},{"@type":"ListItem","position":2,"name":"\u30aa\u30fc\u30eb\u30bb\u30e9\u30df\u30c3\u30af\u30af\u30e9\u30a6\u30f3"}]},{"@type":"WebSite","@id":"https:\/\/www.shining-dc.com.tw\/#website","url":"https:\/\/www.shining-dc.com.tw\/","name":"\u55a8\u7c92\u6676\u7259\u91ab\u8a3a\u6240","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shining-dc.com.tw\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"}]}},"_links":{"self":[{"href":"https:\/\/www.shining-dc.com.tw\/ja\/wp-json\/wp\/v2\/pages\/8867"}],"collection":[{"href":"https:\/\/www.shining-dc.com.tw\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.shining-dc.com.tw\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.shining-dc.com.tw\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shining-dc.com.tw\/ja\/wp-json\/wp\/v2\/comments?post=8867"}],"version-history":[{"count":10,"href":"https:\/\/www.shining-dc.com.tw\/ja\/wp-json\/wp\/v2\/pages\/8867\/revisions"}],"predecessor-version":[{"id":9045,"href":"https:\/\/www.shining-dc.com.tw\/ja\/wp-json\/wp\/v2\/pages\/8867\/revisions\/9045"}],"wp:attachment":[{"href":"https:\/\/www.shining-dc.com.tw\/ja\/wp-json\/wp\/v2\/media?parent=8867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}